{"id":449693,"date":"2026-02-18T20:07:27","date_gmt":"2026-02-19T01:07:27","guid":{"rendered":"https:\/\/autosphere.ca\/?p=449693"},"modified":"2026-02-18T20:07:27","modified_gmt":"2026-02-19T01:07:27","slug":"aapex-2026-appel-de-candidatures-pour-les-sessions-de-formation-a-las-vegas","status":"publish","type":"post","link":"https:\/\/autosphere.ca\/fr\/mecanique\/2026\/02\/18\/aapex-2026-appel-de-candidatures-pour-les-sessions-de-formation-a-las-vegas\/","title":{"rendered":"AAPEX 2026 : Appel de candidatures pour les sessions de formation \u00e0 Las Vegas"},"content":{"rendered":"<p data-path-to-node=\"3\">L&rsquo;AAPEX (Automotive Aftermarket Products Expo) lance un appel de candidatures pour les sessions de formation de son salon annuel, qui se tiendra \u00e0 Las Vegas du 3 au 5 novembre 2026. Les formations doivent \u00eatre ax\u00e9es sur la gestion d&rsquo;entreprise ou sur la formation technique destin\u00e9e aux ateliers de r\u00e9paration ind\u00e9pendants et \u00e0 leurs propri\u00e9taires. La date limite pour soumettre une proposition est le 18 mars 2026.<\/p>\n<p data-path-to-node=\"4\">Certaines sessions interactives se d\u00e9rouleront au Joe\u2019s Garage, un lieu embl\u00e9matique de l&rsquo;AAPEX. Situ\u00e9 directement sur le plancher d&rsquo;exposition, le Joe\u2019s Garage est un centre de service complet \u00e9quip\u00e9 de 10 ponts \u00e9l\u00e9vateurs op\u00e9rationnels. Cet espace est con\u00e7u pour la formation pratique et les d\u00e9monstrations en conditions r\u00e9elles, mettant souvent en avant de nouvelles pi\u00e8ces, outils et \u00e9quipements de service.<\/p>\n<p data-path-to-node=\"4\">\u00ab L&rsquo;ann\u00e9e derni\u00e8re, l&rsquo;AAPEX a accueilli plus de 100 sessions de formation et d\u00e9monstrations de produits. L&rsquo;acc\u00e8s \u00e0 la formation et la d\u00e9couverte de nouveaux produits innovants figurent syst\u00e9matiquement parmi les principales raisons invoqu\u00e9es par nos participants pour visiter le salon \u00bb, a d\u00e9clar\u00e9 Liz Goad, vice-pr\u00e9sidente des \u00e9v\u00e9nements chez MEMA Aftermarket Suppliers.<\/p>\n<p data-path-to-node=\"6\">Selon un sondage r\u00e9alis\u00e9 apr\u00e8s l&rsquo;\u00e9dition 2025, 93 % des participants ayant suivi une formation ont affirm\u00e9 que celle-ci avait r\u00e9pondu \u00e0 leurs attentes (53 %) ou les avait d\u00e9pass\u00e9es (40 %).<\/p>\n<p data-path-to-node=\"6\"><strong>Crit\u00e8res de s\u00e9lection des formations<\/strong><\/p>\n<p data-path-to-node=\"8\">Toutes les propositions seront \u00e9valu\u00e9es par un jury compos\u00e9 de techniciens et de propri\u00e9taires d&rsquo;ateliers ind\u00e9pendants. Les candidats seront inform\u00e9s de la s\u00e9lection \u00e0 la mi-avril.<\/p>\n<p data-path-to-node=\"9\">Les crit\u00e8res de s\u00e9lection incluent :<\/p>\n<ul data-path-to-node=\"10\">\n<li>\n<p data-path-to-node=\"10,0,0\">La pertinence pour la communaut\u00e9 de la r\u00e9paration ind\u00e9pendante ;<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"10,1,0\">La qualit\u00e9 du contenu propos\u00e9 ;<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"10,2,0\">Les objectifs d&rsquo;apprentissage r\u00e9alisables ;<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"10,3,0\">Les qualifications du formateur ou du pr\u00e9sentateur ;<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"10,4,0\">L&rsquo;applicabilit\u00e9 au travail quotidien en atelier ou \u00e0 la carri\u00e8re.<\/p>\n<\/li>\n<\/ul>\n<p data-path-to-node=\"11\">Note importante : Les pr\u00e9sentations \u00e0 caract\u00e8re commercial ou promotionnel ne seront pas retenues.<\/p>\n<p data-path-to-node=\"11\"><strong>Honoraires et frais de d\u00e9placement<\/strong><\/p>\n<p data-path-to-node=\"13\">Reconnaissant que la formation de qualit\u00e9 est un investissement, l&rsquo;AAPEX offre aux pr\u00e9sentateurs s\u00e9lectionn\u00e9s :<\/p>\n<ul data-path-to-node=\"14\">\n<li>\n<p data-path-to-node=\"14,0,0\">L&rsquo;acc\u00e8s gratuit au salon ;<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"14,1,0\">Des honoraires de 500 $ par session (montant fixe, peu importe le nombre d&rsquo;intervenants) ;<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"14,2,0\">Une allocation de 750 $ pour les frais de d\u00e9placement et de s\u00e9jour.<\/p>\n<\/li>\n<\/ul>\n<p data-path-to-node=\"16\">Les conf\u00e9renciers potentiels peuvent soumettre leurs propositions sur le site officiel de l&rsquo;AAPEX. Chaque intervenant peut proposer jusqu&rsquo;\u00e0 six sessions diff\u00e9rentes avant la date limite. Pour toute question sp\u00e9cifique aux formations au Joe\u2019s Garage, vous pouvez \u00e9crire \u00e0 kelly@appexshow.com.<\/p>\n<p data-path-to-node=\"17\">\u00ab Le rythme de l&rsquo;innovation dans la r\u00e9paration s&rsquo;acc\u00e9l\u00e8re, rendant la formation continue essentielle \u00bb, souligne Mark Bogdansky, vice-pr\u00e9sident des salons commerciaux \u00e0 l&rsquo;Auto Care Association. \u00ab L&rsquo;AAPEX s&rsquo;efforce toujours de livrer les meilleurs produits, le meilleur r\u00e9seautage et, bien s\u00fbr, des opportunit\u00e9s \u00e9ducatives de classe mondiale. \u00bb<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;AAPEX (Automotive Aftermarket Products Expo) lance un appel de candidatures pour les sessions de formation de son salon annuel, qui se tiendra \u00e0 Las Vegas du 3 au 5 novembre 2026. Les formations doivent \u00eatre ax\u00e9es sur la gestion d&rsquo;entreprise ou sur la formation technique destin\u00e9e aux ateliers de r\u00e9paration ind\u00e9pendants et \u00e0 leurs propri\u00e9taires&#8230;.<\/p>\n","protected":false},"author":5,"featured_media":449691,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[825,632],"tags":[2700],"class_list":["post-449693","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mecanique-communique","category-mecanique","tag-aapex-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v27.7) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>AAPEX 2026 : Appel de candidatures pour les sessions de formation \u00e0 Las Vegas - Autosphere<\/title>\n<meta name=\"description\" content=\"L&#039;AAPEX (Automotive Aftermarket Products Expo) lance un appel de candidatures pour les sessions de formation de son salon annuel, qui se tiendra \u00e0 Las Vegas du 3 au 5 novembre 2026. Les formations doivent \u00eatre ax\u00e9es sur la gestion d&#039;entreprise ou sur la formation technique destin\u00e9e aux ateliers de r\u00e9paration ind\u00e9pendants et \u00e0 leurs propri\u00e9taires. La date limite pour soumettre une proposition est le 18 mars 2026.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/autosphere.ca\/fr\/mecanique\/2026\/02\/18\/aapex-2026-appel-de-candidatures-pour-les-sessions-de-formation-a-las-vegas\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AAPEX 2026 : Appel de candidatures pour les sessions de formation \u00e0 Las Vegas\" \/>\n<meta property=\"og:description\" content=\"L&#039;AAPEX (Automotive Aftermarket Products Expo) lance un appel de candidatures pour les sessions de formation de son salon annuel, qui se tiendra \u00e0 Las Vegas du 3 au 5 novembre 2026. Les formations doivent \u00eatre ax\u00e9es sur la gestion d&#039;entreprise ou sur la formation technique destin\u00e9e aux ateliers de r\u00e9paration ind\u00e9pendants et \u00e0 leurs propri\u00e9taires. La date limite pour soumettre une proposition est le 18 mars 2026.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/autosphere.ca\/fr\/mecanique\/2026\/02\/18\/aapex-2026-appel-de-candidatures-pour-les-sessions-de-formation-a-las-vegas\/\" \/>\n<meta property=\"og:site_name\" content=\"Autosphere\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/autosphere.ca\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-19T01:07:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/autosphere.ca\/wp-content\/uploads\/2026\/02\/Photo-1-9.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"758\" \/>\n\t<meta property=\"og:image:height\" content=\"585\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Autosphere\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@autosphere_ca\" \/>\n<meta name=\"twitter:site\" content=\"@autosphere_ca\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Autosphere\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/mecanique\\\/2026\\\/02\\\/18\\\/aapex-2026-appel-de-candidatures-pour-les-sessions-de-formation-a-las-vegas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/mecanique\\\/2026\\\/02\\\/18\\\/aapex-2026-appel-de-candidatures-pour-les-sessions-de-formation-a-las-vegas\\\/\"},\"author\":{\"name\":\"Autosphere\",\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/#\\\/schema\\\/person\\\/f8c586ee313be462436e277588bdc643\"},\"headline\":\"AAPEX 2026 : Appel de candidatures pour les sessions de formation \u00e0 Las Vegas\",\"datePublished\":\"2026-02-19T01:07:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/mecanique\\\/2026\\\/02\\\/18\\\/aapex-2026-appel-de-candidatures-pour-les-sessions-de-formation-a-las-vegas\\\/\"},\"wordCount\":497,\"publisher\":{\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/mecanique\\\/2026\\\/02\\\/18\\\/aapex-2026-appel-de-candidatures-pour-les-sessions-de-formation-a-las-vegas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/autosphere.ca\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Photo-1-9.jpg\",\"keywords\":[\"AAPEX\"],\"articleSection\":[\"Communiqu\u00e9 de presse\",\"M\u00e9canique\"],\"inLanguage\":\"fr-FR\",\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/autosphere.ca\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/mecanique\\\/2026\\\/02\\\/18\\\/aapex-2026-appel-de-candidatures-pour-les-sessions-de-formation-a-las-vegas\\\/\",\"url\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/mecanique\\\/2026\\\/02\\\/18\\\/aapex-2026-appel-de-candidatures-pour-les-sessions-de-formation-a-las-vegas\\\/\",\"name\":\"AAPEX 2026 : Appel de candidatures pour les sessions de formation \u00e0 Las Vegas - Autosphere\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/mecanique\\\/2026\\\/02\\\/18\\\/aapex-2026-appel-de-candidatures-pour-les-sessions-de-formation-a-las-vegas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/mecanique\\\/2026\\\/02\\\/18\\\/aapex-2026-appel-de-candidatures-pour-les-sessions-de-formation-a-las-vegas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/autosphere.ca\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Photo-1-9.jpg\",\"datePublished\":\"2026-02-19T01:07:27+00:00\",\"description\":\"L'AAPEX (Automotive Aftermarket Products Expo) lance un appel de candidatures pour les sessions de formation de son salon annuel, qui se tiendra \u00e0 Las Vegas du 3 au 5 novembre 2026. Les formations doivent \u00eatre ax\u00e9es sur la gestion d'entreprise ou sur la formation technique destin\u00e9e aux ateliers de r\u00e9paration ind\u00e9pendants et \u00e0 leurs propri\u00e9taires. La date limite pour soumettre une proposition est le 18 mars 2026.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/mecanique\\\/2026\\\/02\\\/18\\\/aapex-2026-appel-de-candidatures-pour-les-sessions-de-formation-a-las-vegas\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/autosphere.ca\\\/fr\\\/mecanique\\\/2026\\\/02\\\/18\\\/aapex-2026-appel-de-candidatures-pour-les-sessions-de-formation-a-las-vegas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/mecanique\\\/2026\\\/02\\\/18\\\/aapex-2026-appel-de-candidatures-pour-les-sessions-de-formation-a-las-vegas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/autosphere.ca\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Photo-1-9.jpg\",\"contentUrl\":\"https:\\\/\\\/autosphere.ca\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Photo-1-9.jpg\",\"width\":758,\"height\":585},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/mecanique\\\/2026\\\/02\\\/18\\\/aapex-2026-appel-de-candidatures-pour-les-sessions-de-formation-a-las-vegas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Autosphere\",\"item\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00e9canique\",\"item\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/category\\\/mecanique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"AAPEX 2026 : Appel de candidatures pour les sessions de formation \u00e0 Las Vegas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/\",\"name\":\"Autosphere\",\"description\":\"Articles et nouvelles de l&#039;industrie automobile\",\"publisher\":{\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/#organization\",\"name\":\"Autosphere\",\"url\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/autosphere.ca\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/AutosphereLogo-SM.png\",\"contentUrl\":\"https:\\\/\\\/autosphere.ca\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/AutosphereLogo-SM.png\",\"width\":586,\"height\":586,\"caption\":\"Autosphere\"},\"image\":{\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/autosphere.ca\",\"https:\\\/\\\/x.com\\\/autosphere_ca\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/autosphere-en\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/#\\\/schema\\\/person\\\/f8c586ee313be462436e277588bdc643\",\"name\":\"Autosphere\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/autosphere.ca\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/cropped-logo-wheel-rouge-500x500-1-96x96.png\",\"url\":\"https:\\\/\\\/autosphere.ca\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/cropped-logo-wheel-rouge-500x500-1-96x96.png\",\"contentUrl\":\"https:\\\/\\\/autosphere.ca\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/cropped-logo-wheel-rouge-500x500-1-96x96.png\",\"caption\":\"Autosphere\"},\"sameAs\":[\"https:\\\/\\\/autosphere.ca\"],\"url\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/author\\\/autosphere\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"AAPEX 2026 : Appel de candidatures pour les sessions de formation \u00e0 Las Vegas - Autosphere","description":"L'AAPEX (Automotive Aftermarket Products Expo) lance un appel de candidatures pour les sessions de formation de son salon annuel, qui se tiendra \u00e0 Las Vegas du 3 au 5 novembre 2026. Les formations doivent \u00eatre ax\u00e9es sur la gestion d'entreprise ou sur la formation technique destin\u00e9e aux ateliers de r\u00e9paration ind\u00e9pendants et \u00e0 leurs propri\u00e9taires. La date limite pour soumettre une proposition est le 18 mars 2026.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/autosphere.ca\/fr\/mecanique\/2026\/02\/18\/aapex-2026-appel-de-candidatures-pour-les-sessions-de-formation-a-las-vegas\/","og_locale":"fr_FR","og_type":"article","og_title":"AAPEX 2026 : Appel de candidatures pour les sessions de formation \u00e0 Las Vegas","og_description":"L'AAPEX (Automotive Aftermarket Products Expo) lance un appel de candidatures pour les sessions de formation de son salon annuel, qui se tiendra \u00e0 Las Vegas du 3 au 5 novembre 2026. Les formations doivent \u00eatre ax\u00e9es sur la gestion d'entreprise ou sur la formation technique destin\u00e9e aux ateliers de r\u00e9paration ind\u00e9pendants et \u00e0 leurs propri\u00e9taires. La date limite pour soumettre une proposition est le 18 mars 2026.","og_url":"https:\/\/autosphere.ca\/fr\/mecanique\/2026\/02\/18\/aapex-2026-appel-de-candidatures-pour-les-sessions-de-formation-a-las-vegas\/","og_site_name":"Autosphere","article_publisher":"https:\/\/www.facebook.com\/autosphere.ca","article_published_time":"2026-02-19T01:07:27+00:00","og_image":[{"width":758,"height":585,"url":"https:\/\/autosphere.ca\/wp-content\/uploads\/2026\/02\/Photo-1-9.jpg","type":"image\/jpeg"}],"author":"Autosphere","twitter_card":"summary_large_image","twitter_creator":"@autosphere_ca","twitter_site":"@autosphere_ca","twitter_misc":{"\u00c9crit par":"Autosphere","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/autosphere.ca\/fr\/mecanique\/2026\/02\/18\/aapex-2026-appel-de-candidatures-pour-les-sessions-de-formation-a-las-vegas\/#article","isPartOf":{"@id":"https:\/\/autosphere.ca\/fr\/mecanique\/2026\/02\/18\/aapex-2026-appel-de-candidatures-pour-les-sessions-de-formation-a-las-vegas\/"},"author":{"name":"Autosphere","@id":"https:\/\/autosphere.ca\/fr\/#\/schema\/person\/f8c586ee313be462436e277588bdc643"},"headline":"AAPEX 2026 : Appel de candidatures pour les sessions de formation \u00e0 Las Vegas","datePublished":"2026-02-19T01:07:27+00:00","mainEntityOfPage":{"@id":"https:\/\/autosphere.ca\/fr\/mecanique\/2026\/02\/18\/aapex-2026-appel-de-candidatures-pour-les-sessions-de-formation-a-las-vegas\/"},"wordCount":497,"publisher":{"@id":"https:\/\/autosphere.ca\/fr\/#organization"},"image":{"@id":"https:\/\/autosphere.ca\/fr\/mecanique\/2026\/02\/18\/aapex-2026-appel-de-candidatures-pour-les-sessions-de-formation-a-las-vegas\/#primaryimage"},"thumbnailUrl":"https:\/\/autosphere.ca\/wp-content\/uploads\/2026\/02\/Photo-1-9.jpg","keywords":["AAPEX"],"articleSection":["Communiqu\u00e9 de presse","M\u00e9canique"],"inLanguage":"fr-FR","copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/autosphere.ca\/#organization"}},{"@type":"WebPage","@id":"https:\/\/autosphere.ca\/fr\/mecanique\/2026\/02\/18\/aapex-2026-appel-de-candidatures-pour-les-sessions-de-formation-a-las-vegas\/","url":"https:\/\/autosphere.ca\/fr\/mecanique\/2026\/02\/18\/aapex-2026-appel-de-candidatures-pour-les-sessions-de-formation-a-las-vegas\/","name":"AAPEX 2026 : Appel de candidatures pour les sessions de formation \u00e0 Las Vegas - Autosphere","isPartOf":{"@id":"https:\/\/autosphere.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/autosphere.ca\/fr\/mecanique\/2026\/02\/18\/aapex-2026-appel-de-candidatures-pour-les-sessions-de-formation-a-las-vegas\/#primaryimage"},"image":{"@id":"https:\/\/autosphere.ca\/fr\/mecanique\/2026\/02\/18\/aapex-2026-appel-de-candidatures-pour-les-sessions-de-formation-a-las-vegas\/#primaryimage"},"thumbnailUrl":"https:\/\/autosphere.ca\/wp-content\/uploads\/2026\/02\/Photo-1-9.jpg","datePublished":"2026-02-19T01:07:27+00:00","description":"L'AAPEX (Automotive Aftermarket Products Expo) lance un appel de candidatures pour les sessions de formation de son salon annuel, qui se tiendra \u00e0 Las Vegas du 3 au 5 novembre 2026. Les formations doivent \u00eatre ax\u00e9es sur la gestion d'entreprise ou sur la formation technique destin\u00e9e aux ateliers de r\u00e9paration ind\u00e9pendants et \u00e0 leurs propri\u00e9taires. La date limite pour soumettre une proposition est le 18 mars 2026.","breadcrumb":{"@id":"https:\/\/autosphere.ca\/fr\/mecanique\/2026\/02\/18\/aapex-2026-appel-de-candidatures-pour-les-sessions-de-formation-a-las-vegas\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/autosphere.ca\/fr\/mecanique\/2026\/02\/18\/aapex-2026-appel-de-candidatures-pour-les-sessions-de-formation-a-las-vegas\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/autosphere.ca\/fr\/mecanique\/2026\/02\/18\/aapex-2026-appel-de-candidatures-pour-les-sessions-de-formation-a-las-vegas\/#primaryimage","url":"https:\/\/autosphere.ca\/wp-content\/uploads\/2026\/02\/Photo-1-9.jpg","contentUrl":"https:\/\/autosphere.ca\/wp-content\/uploads\/2026\/02\/Photo-1-9.jpg","width":758,"height":585},{"@type":"BreadcrumbList","@id":"https:\/\/autosphere.ca\/fr\/mecanique\/2026\/02\/18\/aapex-2026-appel-de-candidatures-pour-les-sessions-de-formation-a-las-vegas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Autosphere","item":"https:\/\/autosphere.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"M\u00e9canique","item":"https:\/\/autosphere.ca\/fr\/category\/mecanique\/"},{"@type":"ListItem","position":3,"name":"AAPEX 2026 : Appel de candidatures pour les sessions de formation \u00e0 Las Vegas"}]},{"@type":"WebSite","@id":"https:\/\/autosphere.ca\/fr\/#website","url":"https:\/\/autosphere.ca\/fr\/","name":"Autosphere","description":"Articles et nouvelles de l&#039;industrie automobile","publisher":{"@id":"https:\/\/autosphere.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/autosphere.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/autosphere.ca\/fr\/#organization","name":"Autosphere","url":"https:\/\/autosphere.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/autosphere.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/autosphere.ca\/wp-content\/uploads\/2021\/06\/AutosphereLogo-SM.png","contentUrl":"https:\/\/autosphere.ca\/wp-content\/uploads\/2021\/06\/AutosphereLogo-SM.png","width":586,"height":586,"caption":"Autosphere"},"image":{"@id":"https:\/\/autosphere.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/autosphere.ca","https:\/\/x.com\/autosphere_ca","https:\/\/www.linkedin.com\/company\/autosphere-en"]},{"@type":"Person","@id":"https:\/\/autosphere.ca\/fr\/#\/schema\/person\/f8c586ee313be462436e277588bdc643","name":"Autosphere","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/autosphere.ca\/wp-content\/uploads\/2023\/09\/cropped-logo-wheel-rouge-500x500-1-96x96.png","url":"https:\/\/autosphere.ca\/wp-content\/uploads\/2023\/09\/cropped-logo-wheel-rouge-500x500-1-96x96.png","contentUrl":"https:\/\/autosphere.ca\/wp-content\/uploads\/2023\/09\/cropped-logo-wheel-rouge-500x500-1-96x96.png","caption":"Autosphere"},"sameAs":["https:\/\/autosphere.ca"],"url":"https:\/\/autosphere.ca\/fr\/author\/autosphere\/"}]}},"_links":{"self":[{"href":"https:\/\/autosphere.ca\/fr\/wp-json\/wp\/v2\/posts\/449693","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/autosphere.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/autosphere.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/autosphere.ca\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/autosphere.ca\/fr\/wp-json\/wp\/v2\/comments?post=449693"}],"version-history":[{"count":0,"href":"https:\/\/autosphere.ca\/fr\/wp-json\/wp\/v2\/posts\/449693\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/autosphere.ca\/fr\/wp-json\/wp\/v2\/media\/449691"}],"wp:attachment":[{"href":"https:\/\/autosphere.ca\/fr\/wp-json\/wp\/v2\/media?parent=449693"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/autosphere.ca\/fr\/wp-json\/wp\/v2\/categories?post=449693"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/autosphere.ca\/fr\/wp-json\/wp\/v2\/tags?post=449693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}