{"id":380062,"date":"2023-02-15T15:13:27","date_gmt":"2023-02-15T20:13:27","guid":{"rendered":"https:\/\/autosphere.ca\/?p=380062"},"modified":"2023-04-21T11:08:57","modified_gmt":"2023-04-21T15:08:57","slug":"pieces-mecaniques-et-service-dentretien-de-qualite","status":"publish","type":"post","link":"https:\/\/autosphere.ca\/fr\/mecanique\/2023\/02\/15\/pieces-mecaniques-et-service-dentretien-de-qualite\/","title":{"rendered":"Pi\u00e8ces m\u00e9caniques et service d\u2019entretien de qualit\u00e9"},"content":{"rendered":"<p><strong>Avec la raret\u00e9 des v\u00e9hicules neufs et m\u00eame d\u2019occasion et la situation frisant le plein emploi au Qu\u00e9bec, la demande en entretien automobile a le vent dans les voiles.<\/strong><\/p>\n<p>Apr\u00e8s des mois de vache maigre provoqu\u00e9s par la pand\u00e9mie, les automobilistes reprennent la route.<\/p>\n<p>La r\u00e9cente p\u00e9riode de vacances, avec la complexit\u00e9 qui pr\u00e9vaut dans les voyages outre-Atlantique, a vu s\u2019accumuler les kilom\u00e8tres parcourus alors que les touristes se sont rabattus en grand nombre sur les destinations nord-am\u00e9ricaines accessibles par la route.<\/p>\n<h2><b>L\u2019incontournable voiture<\/b><\/h2>\n<p>La reprise des activit\u00e9s \u00e9conomiques combin\u00e9e \u00e0 notre d\u00e9mographie permet d\u2019afficher des statistiques remarquables en mati\u00e8re d\u2019emploi. Et pour se rendre \u00e0 ce travail, on doit avoir acc\u00e8s \u00e0 un v\u00e9hicule fiable, parfois le second v\u00e9hicule familial.<\/p>\n<p>Cette r\u00e9alit\u00e9 fait que les consommateurs recherchent avidement de nouveaux v\u00e9hicules et ceux qui en poss\u00e8dent un veulent le conserver, d\u2019autant que les v\u00e9hicules neufs ne sont encore livr\u00e9s qu\u2019au compte-goutte.<\/p>\n<p>Pour l\u2019atelier de m\u00e9canique ind\u00e9pendant, ces facteurs convergents contribuent \u00e0 remplir les baies de service.<\/p>\n<p>Vous avez acc\u00e8s \u00e0 une belle client\u00e8le qui ne tient qu\u2019\u00e0 vous de fid\u00e9liser. Un client qui veut conserver sa voiture plus longtemps, par choix ou par obligation, devrait \u00eatre de la musique \u00e0 vos oreilles. Vous devez \u00eatre de v\u00e9ritables partenaires \u00e0 ses yeux. U<\/p>\n<p>n client qui poss\u00e8de une voiture depuis trois \u00e0 cinq ans et qui commence \u00e0 regarder pour un remplacement devrait \u00eatre bien inform\u00e9 avant de prendre sa d\u00e9cision.<\/p>\n<p>En ayant le cumulatif des entretiens annuels d\u2019un v\u00e9hicule \u00e9quivalent, vous pourrez lui montrer, noir sur blanc, combien il \u00e9conomisera en entretenant son v\u00e9hicule actuel au lieu de s\u2019engager dans des versements mensuels pour les prochaines ann\u00e9es pour une voiture neuve.<\/p>\n<p>En passant, avec la hausse des prix d\u2019achat des voitures aujourd\u2019hui il va en co\u00fbter beaucoup plus cher \u00e0 votre client s\u2019il esp\u00e8re avoir simplement une voiture \u00e9quivalente.<\/p>\n<h2><b>Optez pour la qualit\u00e9<\/b><\/h2>\n<p>Parlant de co\u00fbts, j\u2019invite les conseillers au comptoir \u00e0 arr\u00eater de d\u00e9cider pour le client. Qui vous dit que le propri\u00e9taire d\u2019une voiture de dix ou douze ans veut n\u00e9cessairement la pi\u00e8ce la moins ch\u00e8re ou l\u2019\u00e9quipement bas de gamme\u00a0?<\/p>\n<p>Un client qui aime son v\u00e9hicule, qui l\u2019a entretenu correctement et souhaite le conserver longtemps, m\u00e9rite qu\u2019on lui propose des pi\u00e8ces de qualit\u00e9 et des services d\u2019entretien pr\u00e9ventif \u00e0 la hauteur. Il est bien plac\u00e9 pour comprendre que sur la dur\u00e9e de vie de son v\u00e9hicule, la pi\u00e8ce de qualit\u00e9 s\u2019av\u00e8re toujours plus rentable \u00e0 la longue.<\/p>\n<p>Des gestes comme un bon antirouille, un nettoyage du syst\u00e8me de ventilation et le remplacement du filtre d\u2019habitacle qui vont \u00e9liminer les mauvaises odeurs ou encore le remplacement d\u2019une suspension en fin de vie vont contribuer \u00e0 redonner au conducteur le plaisir de conduire qu\u2019il avait \u00e9prouv\u00e9 au jour de l\u2019achat.<\/p>\n<p>Les acteurs du march\u00e9 secondaire savent que les pi\u00e8ces de remplacement disponibles aujourd\u2019hui offrent non seulement une couverture \u00e9largie, mais souvent une qualit\u00e9 ou une conception surpassant celles d\u2019origine.<\/p>\n<p>Quand on pense suspension, direction ou encore freinage, la possibilit\u00e9 d\u2019en offrir davantage \u00e0 nos clients pour am\u00e9liorer leur exp\u00e9rience de conduite et surtout, leur s\u00e9curit\u00e9 et celle de tous les utilisateurs de la route, est un \u00e9l\u00e9ment qui me tient \u00e0 c\u0153ur et que vous devez partager.<\/p>\n<p>En d\u00e9veloppant un lien de confiance avec votre client, notamment en r\u00e9partissant les travaux selon leur urgence, vous poserez les gestes qu\u2019il faut pour que ce v\u00e9hicule reste sur la route, en toute s\u00e9curit\u00e9, tr\u00e8s longtemps.<\/p>\n<p>C\u2019est un plus pour vous, un plus pour votre client et aussi, mentionnons-le, un plus pour la protection de notre environnement et de nos ressources.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avec la raret\u00e9 des v\u00e9hicules neufs et m\u00eame d\u2019occasion et la situation frisant le plein emploi au Qu\u00e9bec, la demande en entretien automobile a le vent dans les voiles. Apr\u00e8s des mois de vache maigre provoqu\u00e9s par la pand\u00e9mie, les automobilistes reprennent la route. La r\u00e9cente p\u00e9riode de vacances, avec la complexit\u00e9 qui pr\u00e9vaut dans&#8230;<\/p>\n","protected":false},"author":142,"featured_media":366322,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[810,632,5125],"tags":[837],"class_list":["post-380062","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chroniques-actualite-mecanique","category-mecanique","category-pieces-composantes","tag-entretien-et-reparation-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v27.7) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Pi\u00e8ces m\u00e9caniques et service d\u2019entretien de qualit\u00e9 - Autosphere<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/autosphere.ca\/fr\/mecanique\/2023\/02\/15\/pieces-mecaniques-et-service-dentretien-de-qualite\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pi\u00e8ces m\u00e9caniques et service d\u2019entretien de qualit\u00e9\" \/>\n<meta property=\"og:description\" content=\"Avec la raret\u00e9 des v\u00e9hicules neufs et m\u00eame d\u2019occasion et la situation frisant le plein emploi au Qu\u00e9bec, la demande en entretien automobile a le vent dans les voiles. Apr\u00e8s des mois de vache maigre provoqu\u00e9s par la pand\u00e9mie, les automobilistes reprennent la route. La r\u00e9cente p\u00e9riode de vacances, avec la complexit\u00e9 qui pr\u00e9vaut dans...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/autosphere.ca\/fr\/mecanique\/2023\/02\/15\/pieces-mecaniques-et-service-dentretien-de-qualite\/\" \/>\n<meta property=\"og:site_name\" content=\"Autosphere\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/autosphere.ca\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-15T20:13:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-21T15:08:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/autosphere.ca\/wp-content\/uploads\/2022\/07\/Andre-Gamelin.jpg_WP.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"758\" \/>\n\t<meta property=\"og:image:height\" content=\"585\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Andr\u00e9 Gamelin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@autosphere_ca\" \/>\n<meta name=\"twitter:site\" content=\"@autosphere_ca\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andr\u00e9 Gamelin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/mecanique\\\/2023\\\/02\\\/15\\\/pieces-mecaniques-et-service-dentretien-de-qualite\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/mecanique\\\/2023\\\/02\\\/15\\\/pieces-mecaniques-et-service-dentretien-de-qualite\\\/\"},\"author\":{\"name\":\"Andr\u00e9 Gamelin\",\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/#\\\/schema\\\/person\\\/d5a16a346ce750aeaadd28896508de0d\"},\"headline\":\"Pi\u00e8ces m\u00e9caniques et service d\u2019entretien de qualit\u00e9\",\"datePublished\":\"2023-02-15T20:13:27+00:00\",\"dateModified\":\"2023-04-21T15:08:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/mecanique\\\/2023\\\/02\\\/15\\\/pieces-mecaniques-et-service-dentretien-de-qualite\\\/\"},\"wordCount\":687,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/mecanique\\\/2023\\\/02\\\/15\\\/pieces-mecaniques-et-service-dentretien-de-qualite\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/autosphere.ca\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Andre-Gamelin.jpg_WP.jpg\",\"keywords\":[\"Entretien et r\u00e9paration\"],\"articleSection\":[\"Actualit\u00e9s m\u00e9caniques\",\"M\u00e9canique\",\"Pi\u00e8ces et composants m\u00e9caniques\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/autosphere.ca\\\/fr\\\/mecanique\\\/2023\\\/02\\\/15\\\/pieces-mecaniques-et-service-dentretien-de-qualite\\\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/autosphere.ca\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/mecanique\\\/2023\\\/02\\\/15\\\/pieces-mecaniques-et-service-dentretien-de-qualite\\\/\",\"url\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/mecanique\\\/2023\\\/02\\\/15\\\/pieces-mecaniques-et-service-dentretien-de-qualite\\\/\",\"name\":\"Pi\u00e8ces m\u00e9caniques et service d\u2019entretien de qualit\u00e9 - Autosphere\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/mecanique\\\/2023\\\/02\\\/15\\\/pieces-mecaniques-et-service-dentretien-de-qualite\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/mecanique\\\/2023\\\/02\\\/15\\\/pieces-mecaniques-et-service-dentretien-de-qualite\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/autosphere.ca\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Andre-Gamelin.jpg_WP.jpg\",\"datePublished\":\"2023-02-15T20:13:27+00:00\",\"dateModified\":\"2023-04-21T15:08:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/mecanique\\\/2023\\\/02\\\/15\\\/pieces-mecaniques-et-service-dentretien-de-qualite\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/autosphere.ca\\\/fr\\\/mecanique\\\/2023\\\/02\\\/15\\\/pieces-mecaniques-et-service-dentretien-de-qualite\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/mecanique\\\/2023\\\/02\\\/15\\\/pieces-mecaniques-et-service-dentretien-de-qualite\\\/#primaryimage\",\"url\":\"https:\\\/\\\/autosphere.ca\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Andre-Gamelin.jpg_WP.jpg\",\"contentUrl\":\"https:\\\/\\\/autosphere.ca\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Andre-Gamelin.jpg_WP.jpg\",\"width\":758,\"height\":585},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/mecanique\\\/2023\\\/02\\\/15\\\/pieces-mecaniques-et-service-dentretien-de-qualite\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Autosphere\",\"item\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00e9canique\",\"item\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/category\\\/mecanique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pi\u00e8ces m\u00e9caniques et service d\u2019entretien de qualit\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/\",\"name\":\"Autosphere\",\"description\":\"Articles et nouvelles de l&#039;industrie automobile\",\"publisher\":{\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/#organization\",\"name\":\"Autosphere\",\"url\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/autosphere.ca\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/AutosphereLogo-SM.png\",\"contentUrl\":\"https:\\\/\\\/autosphere.ca\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/AutosphereLogo-SM.png\",\"width\":586,\"height\":586,\"caption\":\"Autosphere\"},\"image\":{\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/autosphere.ca\",\"https:\\\/\\\/x.com\\\/autosphere_ca\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/autosphere-en\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/#\\\/schema\\\/person\\\/d5a16a346ce750aeaadd28896508de0d\",\"name\":\"Andr\u00e9 Gamelin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/autosphere.ca\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-Andre-Gamelin.jpg_WP-96x96.jpg\",\"url\":\"https:\\\/\\\/autosphere.ca\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-Andre-Gamelin.jpg_WP-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/autosphere.ca\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/cropped-Andre-Gamelin.jpg_WP-96x96.jpg\",\"caption\":\"Andr\u00e9 Gamelin\"},\"description\":\"Andr\u00e9 Gamelin est propri\u00e9taire des magasins Pi\u00e8ces d\u2019auto Super de Saint-Hubert et de Saint-Jean-sur-Richelieu. Questions et commentaires : andre.gamelin@pasuper.com. Andr\u00e9 Gamelin is the owner of Pi\u00e8ces d\u2019auto Super stores in Saint-Hubert and Saint-Jean-sur-Richelieu. Questions and comments: andre.gamelin@pasuper.com\",\"sameAs\":[\"https:\\\/\\\/autosphere.ca\"],\"url\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/author\\\/agamelin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Pi\u00e8ces m\u00e9caniques et service d\u2019entretien de qualit\u00e9 - Autosphere","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/autosphere.ca\/fr\/mecanique\/2023\/02\/15\/pieces-mecaniques-et-service-dentretien-de-qualite\/","og_locale":"fr_FR","og_type":"article","og_title":"Pi\u00e8ces m\u00e9caniques et service d\u2019entretien de qualit\u00e9","og_description":"Avec la raret\u00e9 des v\u00e9hicules neufs et m\u00eame d\u2019occasion et la situation frisant le plein emploi au Qu\u00e9bec, la demande en entretien automobile a le vent dans les voiles. Apr\u00e8s des mois de vache maigre provoqu\u00e9s par la pand\u00e9mie, les automobilistes reprennent la route. La r\u00e9cente p\u00e9riode de vacances, avec la complexit\u00e9 qui pr\u00e9vaut dans...","og_url":"https:\/\/autosphere.ca\/fr\/mecanique\/2023\/02\/15\/pieces-mecaniques-et-service-dentretien-de-qualite\/","og_site_name":"Autosphere","article_publisher":"https:\/\/www.facebook.com\/autosphere.ca","article_published_time":"2023-02-15T20:13:27+00:00","article_modified_time":"2023-04-21T15:08:57+00:00","og_image":[{"width":758,"height":585,"url":"https:\/\/autosphere.ca\/wp-content\/uploads\/2022\/07\/Andre-Gamelin.jpg_WP.jpg","type":"image\/jpeg"}],"author":"Andr\u00e9 Gamelin","twitter_card":"summary_large_image","twitter_creator":"@autosphere_ca","twitter_site":"@autosphere_ca","twitter_misc":{"\u00c9crit par":"Andr\u00e9 Gamelin","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/autosphere.ca\/fr\/mecanique\/2023\/02\/15\/pieces-mecaniques-et-service-dentretien-de-qualite\/#article","isPartOf":{"@id":"https:\/\/autosphere.ca\/fr\/mecanique\/2023\/02\/15\/pieces-mecaniques-et-service-dentretien-de-qualite\/"},"author":{"name":"Andr\u00e9 Gamelin","@id":"https:\/\/autosphere.ca\/fr\/#\/schema\/person\/d5a16a346ce750aeaadd28896508de0d"},"headline":"Pi\u00e8ces m\u00e9caniques et service d\u2019entretien de qualit\u00e9","datePublished":"2023-02-15T20:13:27+00:00","dateModified":"2023-04-21T15:08:57+00:00","mainEntityOfPage":{"@id":"https:\/\/autosphere.ca\/fr\/mecanique\/2023\/02\/15\/pieces-mecaniques-et-service-dentretien-de-qualite\/"},"wordCount":687,"commentCount":0,"publisher":{"@id":"https:\/\/autosphere.ca\/fr\/#organization"},"image":{"@id":"https:\/\/autosphere.ca\/fr\/mecanique\/2023\/02\/15\/pieces-mecaniques-et-service-dentretien-de-qualite\/#primaryimage"},"thumbnailUrl":"https:\/\/autosphere.ca\/wp-content\/uploads\/2022\/07\/Andre-Gamelin.jpg_WP.jpg","keywords":["Entretien et r\u00e9paration"],"articleSection":["Actualit\u00e9s m\u00e9caniques","M\u00e9canique","Pi\u00e8ces et composants m\u00e9caniques"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/autosphere.ca\/fr\/mecanique\/2023\/02\/15\/pieces-mecaniques-et-service-dentretien-de-qualite\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/autosphere.ca\/#organization"}},{"@type":"WebPage","@id":"https:\/\/autosphere.ca\/fr\/mecanique\/2023\/02\/15\/pieces-mecaniques-et-service-dentretien-de-qualite\/","url":"https:\/\/autosphere.ca\/fr\/mecanique\/2023\/02\/15\/pieces-mecaniques-et-service-dentretien-de-qualite\/","name":"Pi\u00e8ces m\u00e9caniques et service d\u2019entretien de qualit\u00e9 - Autosphere","isPartOf":{"@id":"https:\/\/autosphere.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/autosphere.ca\/fr\/mecanique\/2023\/02\/15\/pieces-mecaniques-et-service-dentretien-de-qualite\/#primaryimage"},"image":{"@id":"https:\/\/autosphere.ca\/fr\/mecanique\/2023\/02\/15\/pieces-mecaniques-et-service-dentretien-de-qualite\/#primaryimage"},"thumbnailUrl":"https:\/\/autosphere.ca\/wp-content\/uploads\/2022\/07\/Andre-Gamelin.jpg_WP.jpg","datePublished":"2023-02-15T20:13:27+00:00","dateModified":"2023-04-21T15:08:57+00:00","breadcrumb":{"@id":"https:\/\/autosphere.ca\/fr\/mecanique\/2023\/02\/15\/pieces-mecaniques-et-service-dentretien-de-qualite\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/autosphere.ca\/fr\/mecanique\/2023\/02\/15\/pieces-mecaniques-et-service-dentretien-de-qualite\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/autosphere.ca\/fr\/mecanique\/2023\/02\/15\/pieces-mecaniques-et-service-dentretien-de-qualite\/#primaryimage","url":"https:\/\/autosphere.ca\/wp-content\/uploads\/2022\/07\/Andre-Gamelin.jpg_WP.jpg","contentUrl":"https:\/\/autosphere.ca\/wp-content\/uploads\/2022\/07\/Andre-Gamelin.jpg_WP.jpg","width":758,"height":585},{"@type":"BreadcrumbList","@id":"https:\/\/autosphere.ca\/fr\/mecanique\/2023\/02\/15\/pieces-mecaniques-et-service-dentretien-de-qualite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Autosphere","item":"https:\/\/autosphere.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"M\u00e9canique","item":"https:\/\/autosphere.ca\/fr\/category\/mecanique\/"},{"@type":"ListItem","position":3,"name":"Pi\u00e8ces m\u00e9caniques et service d\u2019entretien de qualit\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/autosphere.ca\/fr\/#website","url":"https:\/\/autosphere.ca\/fr\/","name":"Autosphere","description":"Articles et nouvelles de l&#039;industrie automobile","publisher":{"@id":"https:\/\/autosphere.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/autosphere.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/autosphere.ca\/fr\/#organization","name":"Autosphere","url":"https:\/\/autosphere.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/autosphere.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/autosphere.ca\/wp-content\/uploads\/2021\/06\/AutosphereLogo-SM.png","contentUrl":"https:\/\/autosphere.ca\/wp-content\/uploads\/2021\/06\/AutosphereLogo-SM.png","width":586,"height":586,"caption":"Autosphere"},"image":{"@id":"https:\/\/autosphere.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/autosphere.ca","https:\/\/x.com\/autosphere_ca","https:\/\/www.linkedin.com\/company\/autosphere-en"]},{"@type":"Person","@id":"https:\/\/autosphere.ca\/fr\/#\/schema\/person\/d5a16a346ce750aeaadd28896508de0d","name":"Andr\u00e9 Gamelin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/autosphere.ca\/wp-content\/uploads\/2022\/07\/cropped-Andre-Gamelin.jpg_WP-96x96.jpg","url":"https:\/\/autosphere.ca\/wp-content\/uploads\/2022\/07\/cropped-Andre-Gamelin.jpg_WP-96x96.jpg","contentUrl":"https:\/\/autosphere.ca\/wp-content\/uploads\/2022\/07\/cropped-Andre-Gamelin.jpg_WP-96x96.jpg","caption":"Andr\u00e9 Gamelin"},"description":"Andr\u00e9 Gamelin est propri\u00e9taire des magasins Pi\u00e8ces d\u2019auto Super de Saint-Hubert et de Saint-Jean-sur-Richelieu. Questions et commentaires : andre.gamelin@pasuper.com. Andr\u00e9 Gamelin is the owner of Pi\u00e8ces d\u2019auto Super stores in Saint-Hubert and Saint-Jean-sur-Richelieu. Questions and comments: andre.gamelin@pasuper.com","sameAs":["https:\/\/autosphere.ca"],"url":"https:\/\/autosphere.ca\/fr\/author\/agamelin\/"}]}},"_links":{"self":[{"href":"https:\/\/autosphere.ca\/fr\/wp-json\/wp\/v2\/posts\/380062","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/autosphere.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/autosphere.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/autosphere.ca\/fr\/wp-json\/wp\/v2\/users\/142"}],"replies":[{"embeddable":true,"href":"https:\/\/autosphere.ca\/fr\/wp-json\/wp\/v2\/comments?post=380062"}],"version-history":[{"count":0,"href":"https:\/\/autosphere.ca\/fr\/wp-json\/wp\/v2\/posts\/380062\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/autosphere.ca\/fr\/wp-json\/wp\/v2\/media\/366322"}],"wp:attachment":[{"href":"https:\/\/autosphere.ca\/fr\/wp-json\/wp\/v2\/media?parent=380062"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/autosphere.ca\/fr\/wp-json\/wp\/v2\/categories?post=380062"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/autosphere.ca\/fr\/wp-json\/wp\/v2\/tags?post=380062"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}