{"id":378618,"date":"2023-01-24T17:16:33","date_gmt":"2023-01-24T22:16:33","guid":{"rendered":"https:\/\/autosphere.ca\/?p=378618"},"modified":"2023-01-24T17:16:33","modified_gmt":"2023-01-24T22:16:33","slug":"reparer-un-systeme-de-ventilation-defaillant","status":"publish","type":"post","link":"https:\/\/autosphere.ca\/fr\/mecanique\/2023\/01\/24\/reparer-un-systeme-de-ventilation-defaillant\/","title":{"rendered":"R\u00e9parer un syst\u00e8me de ventilation d\u00e9faillant"},"content":{"rendered":"<p><strong>Dans le cas que je vous pr\u00e9sente aujourd&rsquo;hui, comprendre le fonctionnement du syst\u00e8me \u00e9tait essentiel pour r\u00e9soudre le probl\u00e8me.<\/strong><\/p>\n<p>Une mini-fourgonnette Toyota Sienna 2018 nous a \u00e9t\u00e9 amen\u00e9e, le client se plaignant que le ventilateur \u00e9tait bloqu\u00e9 sur la position haute, avec un affichage vide du panneau de contr\u00f4le HVAC (syst\u00e8me de chauffage, de ventilation et de conditionnement d&rsquo;air). Le r\u00e9tro-\u00e9clairage du panneau de commande \u00e9tait allum\u00e9 mais l&rsquo;\u00e9cran lui-m\u00eame \u00e9tait vide.<\/p>\n<p>Nous avons jet\u00e9 un coup d&rsquo;\u0153il rapide \u00e0 un sch\u00e9ma de c\u00e2blage pour voir \u00e0 quoi ressemblaient les composants du syst\u00e8me et quels modules \u00e9taient impliqu\u00e9s. Nous avons d\u00e9couvert qu&rsquo;il y avait un contr\u00f4leur central appel\u00e9 \u00ab AC Amplifier Assembly \u00bb ainsi qu&rsquo;un panneau de contr\u00f4le avant et arri\u00e8re qui communique avec l&rsquo;amplificateur AC via un bus LIN. Comme les panneaux de commande sont reli\u00e9s \u00e0 l&rsquo;amplificateur CA et que l&rsquo;amplificateur se trouve sur le bus de donn\u00e9es principal du v\u00e9hicule, l&rsquo;amplificateur a \u00e9t\u00e9 contr\u00f4l\u00e9 pour d\u00e9tecter les codes. Nous avons r\u00e9cup\u00e9r\u00e9 les codes B14B2 (perte de communication avec le panneau avant LIN) et B B14B3 (perte de communication avec le panneau arri\u00e8re LIN).<\/p>\n<h2><b>Test pour les circuits ouverts et les courts-circuits<\/b><\/h2>\n<p>Nous avons lu l&rsquo;arbre des probl\u00e8mes du code B14B2 pour voir ce que le fabricant voulait que nous testions ou remplacions. En gros, les instructions sugg\u00e9raient de v\u00e9rifier l&rsquo;alimentation et la mise \u00e0 la terre du panneau de commande avant et de tester les circuits LIN pour d\u00e9tecter les circuits ouverts et les courts-circuits. Si cela a fonctionne, l&rsquo;\u00e9tape suivante consiste \u00e0 remplacer le panneau de commande avant, si ce<\/p>\n<figure id=\"attachment_378602\" aria-describedby=\"caption-attachment-378602\" style=\"width: 479px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-378601 \" src=\"https:\/\/autosphere.ca\/wp-content\/uploads\/2023\/01\/Photo-2-Fixing-a-Hobbled-Toyota-HVAC-System-Toyota-Sienna-CRD-ToyotaF-600x400.jpg\" alt=\"\" width=\"479\" height=\"319\" srcset=\"https:\/\/autosphere.ca\/wp-content\/uploads\/2023\/01\/Photo-2-Fixing-a-Hobbled-Toyota-HVAC-System-Toyota-Sienna-CRD-ToyotaF-600x400.jpg 600w, https:\/\/autosphere.ca\/wp-content\/uploads\/2023\/01\/Photo-2-Fixing-a-Hobbled-Toyota-HVAC-System-Toyota-Sienna-CRD-ToyotaF-135x90.jpg 135w\" sizes=\"auto, (max-width: 479px) 100vw, 479px\" \/><figcaption id=\"caption-attachment-378602\" class=\"wp-caption-text\">Toyota Sienna 2018. Photo Toyota<\/figcaption><\/figure>\n<p>la ne r\u00e9sout pas le probl\u00e8me, la solution suivante consiste \u00e0 remplacer l&rsquo;amplificateur.<\/p>\n<p>Notre test du c\u00e2blage du panneau de contr\u00f4le frontal n&rsquo;a r\u00e9v\u00e9l\u00e9 aucun d\u00e9faut et nous n&rsquo;avons rien trouv\u00e9 d&rsquo;anormal dans le bus LIN. Nous avons d\u00e9cid\u00e9 d&rsquo;examiner le bus LIN pour voir \u00e0 quoi ressemble la signature LIN. Le bus LIN a \u00e9t\u00e9 court-circuit\u00e9 \u00e0 la masse et a montr\u00e9 une ligne plate \u00e0 0 volt. Lorsque l&rsquo;amplificateur a \u00e9t\u00e9 d\u00e9branch\u00e9, le bus LIN a saut\u00e9 jusqu&rsquo;\u00e0 la tension de polarisation. Nous avons conclu qu&rsquo;il y avait un manque dans l&rsquo;amplificateur, nous avons donc command\u00e9 et install\u00e9 un nouvel amplificateur. Malheureusement, le nouvel amplificateur n&rsquo;a pas r\u00e9gl\u00e9 le probl\u00e8me.<\/p>\n<p>\u00c0 ce stade, nous avons d\u00fb prendre du recul et r\u00e9\u00e9valuer ce que nous faisions. Ce qui \u00e9tait vraiment n\u00e9cessaire ici \u00e9tait une meilleure description du fonctionnement du bus LIN car il y a un probl\u00e8me \u00e9vident avec le bus. LIN utilise un bus de type ma\u00eetre et esclave, dans ce cas, l&rsquo;amplificateur est le ma\u00eetre, et les deux panneaux de contr\u00f4le sont les esclaves. Cela signifie que toute communication doit passer par le Ma\u00eetre. La plupart des syst\u00e8mes qui utilisent LIN sur un bus multi-modules, c\u00e2blent les fils du bus ensemble dans un circuit parall\u00e8le externe au ma\u00eetre. Ce n&rsquo;\u00e9tait pas le cas avec notre Toyota, puisque les circuits LIN sont connect\u00e9s en interne dans l&rsquo;amplificateur. Une fois que nous avons compris comment le syst\u00e8me fonctionnait, nous avons su que nous devions nous pencher sur le LIN arri\u00e8re. Il s&rsquo;agissait de fils s\u00e9par\u00e9s allant dans l&rsquo;amplificateur et n&rsquo;\u00e9taient pas mentionn\u00e9s dans l&rsquo;\u00e9valuation de l&rsquo;arbre des probl\u00e8mes pour le code B14B2.<\/p>\n<h2><b>Le syst\u00e8me CVC r\u00e9pond<\/b><\/h2>\n<p>Nous avons examin\u00e9 le LIN arri\u00e8re et avons d\u00e9couvert qu&rsquo;il \u00e9tait \u00e9galement court-circuit\u00e9. Apr\u00e8s une v\u00e9rification rapide pour voir si cela \u00e9tait la cause de notre probl\u00e8me, le LIN arri\u00e8re a \u00e9t\u00e9 d\u00e9connect\u00e9 de l&rsquo;amplificateur. D\u00e8s que le LIN arri\u00e8re a \u00e9t\u00e9 retir\u00e9 de l&rsquo;amplificateur, la t\u00eate de contr\u00f4le avant est revenue \u00e0 la vie et le syst\u00e8me CVC a r\u00e9pondu aux entr\u00e9es du panneau de contr\u00f4le, confirmant que nous avions un probl\u00e8me dans le LIN arri\u00e8re.<\/p>\n<p>\u00c0 ce stade, nous avons commenc\u00e9 \u00e0 v\u00e9rifier le c\u00e2blage de la t\u00eate de commande arri\u00e8re et nous avons d\u00e9couvert que si nous tirions sur la garniture de toit, le bus LIN revenait \u00e0 la vie. Il s&rsquo;est av\u00e9r\u00e9 que des souris avaient rong\u00e9 le c\u00e2blage, court-circuitant le bus LIN. Outre le fait que la garniture de toit a d\u00fb \u00eatre retir\u00e9e pour acc\u00e9der au c\u00e2blage, une simple r\u00e9paration du c\u00e2blage a suffi pour r\u00e9soudre ce probl\u00e8me.<\/p>\n<p>Nous avons fait quelques erreurs sur ce cas. Si nous avions choisi le code B14B3 au lieu du code B14B2, l&rsquo;arbre des probl\u00e8mes aurait fonctionn\u00e9. Deuxi\u00e8mement, si nous avions r\u00e9alis\u00e9 que les fils du bus LIN \u00e9taient connect\u00e9s en interne dans l&rsquo;amplificateur, nous aurions v\u00e9rifi\u00e9 le LIN arri\u00e8re plus t\u00f4t. L&rsquo;essentiel ici est de s&rsquo;assurer que vous comprenez tous les aspects du syst\u00e8me que vous essayez de diagnostiquer.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans le cas que je vous pr\u00e9sente aujourd&rsquo;hui, comprendre le fonctionnement du syst\u00e8me \u00e9tait essentiel pour r\u00e9soudre le probl\u00e8me. Une mini-fourgonnette Toyota Sienna 2018 nous a \u00e9t\u00e9 amen\u00e9e, le client se plaignant que le ventilateur \u00e9tait bloqu\u00e9 sur la position haute, avec un affichage vide du panneau de contr\u00f4le HVAC (syst\u00e8me de chauffage, de ventilation&#8230;<\/p>\n","protected":false},"author":179,"featured_media":368042,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[810,632],"tags":[837],"class_list":["post-378618","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chroniques-actualite-mecanique","category-mecanique","tag-entretien-et-reparation-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v27.7) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>R\u00e9parer un syst\u00e8me de ventilation d\u00e9faillant - Autosphere<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/autosphere.ca\/fr\/mecanique\/2023\/01\/24\/reparer-un-systeme-de-ventilation-defaillant\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R\u00e9parer un syst\u00e8me de ventilation d\u00e9faillant\" \/>\n<meta property=\"og:description\" content=\"Dans le cas que je vous pr\u00e9sente aujourd&rsquo;hui, comprendre le fonctionnement du syst\u00e8me \u00e9tait essentiel pour r\u00e9soudre le probl\u00e8me. Une mini-fourgonnette Toyota Sienna 2018 nous a \u00e9t\u00e9 amen\u00e9e, le client se plaignant que le ventilateur \u00e9tait bloqu\u00e9 sur la position haute, avec un affichage vide du panneau de contr\u00f4le HVAC (syst\u00e8me de chauffage, de ventilation...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/autosphere.ca\/fr\/mecanique\/2023\/01\/24\/reparer-un-systeme-de-ventilation-defaillant\/\" \/>\n<meta property=\"og:site_name\" content=\"Autosphere\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/autosphere.ca\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-24T22:16:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/autosphere.ca\/wp-content\/uploads\/2022\/08\/Mark-Lemay.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"758\" \/>\n\t<meta property=\"og:image:height\" content=\"585\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mark Lemay\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@autosphere_ca\" \/>\n<meta name=\"twitter:site\" content=\"@autosphere_ca\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mark Lemay\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/mecanique\\\/2023\\\/01\\\/24\\\/reparer-un-systeme-de-ventilation-defaillant\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/mecanique\\\/2023\\\/01\\\/24\\\/reparer-un-systeme-de-ventilation-defaillant\\\/\"},\"author\":{\"name\":\"Mark Lemay\",\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/#\\\/schema\\\/person\\\/d077f1cf0dd6393fef2f239b7b4fbbca\"},\"headline\":\"R\u00e9parer un syst\u00e8me de ventilation d\u00e9faillant\",\"datePublished\":\"2023-01-24T22:16:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/mecanique\\\/2023\\\/01\\\/24\\\/reparer-un-systeme-de-ventilation-defaillant\\\/\"},\"wordCount\":910,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/mecanique\\\/2023\\\/01\\\/24\\\/reparer-un-systeme-de-ventilation-defaillant\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/autosphere.ca\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Mark-Lemay.jpg\",\"keywords\":[\"Entretien et r\u00e9paration\"],\"articleSection\":[\"Actualit\u00e9s m\u00e9caniques\",\"M\u00e9canique\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/autosphere.ca\\\/fr\\\/mecanique\\\/2023\\\/01\\\/24\\\/reparer-un-systeme-de-ventilation-defaillant\\\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/autosphere.ca\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/mecanique\\\/2023\\\/01\\\/24\\\/reparer-un-systeme-de-ventilation-defaillant\\\/\",\"url\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/mecanique\\\/2023\\\/01\\\/24\\\/reparer-un-systeme-de-ventilation-defaillant\\\/\",\"name\":\"R\u00e9parer un syst\u00e8me de ventilation d\u00e9faillant - Autosphere\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/mecanique\\\/2023\\\/01\\\/24\\\/reparer-un-systeme-de-ventilation-defaillant\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/mecanique\\\/2023\\\/01\\\/24\\\/reparer-un-systeme-de-ventilation-defaillant\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/autosphere.ca\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Mark-Lemay.jpg\",\"datePublished\":\"2023-01-24T22:16:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/mecanique\\\/2023\\\/01\\\/24\\\/reparer-un-systeme-de-ventilation-defaillant\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/autosphere.ca\\\/fr\\\/mecanique\\\/2023\\\/01\\\/24\\\/reparer-un-systeme-de-ventilation-defaillant\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/mecanique\\\/2023\\\/01\\\/24\\\/reparer-un-systeme-de-ventilation-defaillant\\\/#primaryimage\",\"url\":\"https:\\\/\\\/autosphere.ca\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Mark-Lemay.jpg\",\"contentUrl\":\"https:\\\/\\\/autosphere.ca\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Mark-Lemay.jpg\",\"width\":758,\"height\":585,\"caption\":\"Mark Lemay, Pr\u00e9sident, Auto Aide Technical Services. Source : Mark Lemay\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/mecanique\\\/2023\\\/01\\\/24\\\/reparer-un-systeme-de-ventilation-defaillant\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Autosphere\",\"item\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00e9canique\",\"item\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/category\\\/mecanique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"R\u00e9parer un syst\u00e8me de ventilation d\u00e9faillant\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/\",\"name\":\"Autosphere\",\"description\":\"Articles et nouvelles de l&#039;industrie automobile\",\"publisher\":{\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/#organization\",\"name\":\"Autosphere\",\"url\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/autosphere.ca\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/AutosphereLogo-SM.png\",\"contentUrl\":\"https:\\\/\\\/autosphere.ca\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/AutosphereLogo-SM.png\",\"width\":586,\"height\":586,\"caption\":\"Autosphere\"},\"image\":{\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/autosphere.ca\",\"https:\\\/\\\/x.com\\\/autosphere_ca\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/autosphere-en\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/#\\\/schema\\\/person\\\/d077f1cf0dd6393fef2f239b7b4fbbca\",\"name\":\"Mark Lemay\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/autosphere.ca\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/cropped-Mark-Lemay-96x96.jpg\",\"url\":\"https:\\\/\\\/autosphere.ca\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/cropped-Mark-Lemay-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/autosphere.ca\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/cropped-Mark-Lemay-96x96.jpg\",\"caption\":\"Mark Lemay\"},\"description\":\"Mark Lemay is President of Auto Aide Technical Services. You can reach him at: markl@autoaide.ca Mark Lemay est le pr\u00e9sident de Auto Aide Technical Services. Vous pouvez le joindre \u00e0 l\u2019adresse suivante : markl@autoaide.ca\",\"url\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/author\\\/mlemay\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"R\u00e9parer un syst\u00e8me de ventilation d\u00e9faillant - Autosphere","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/autosphere.ca\/fr\/mecanique\/2023\/01\/24\/reparer-un-systeme-de-ventilation-defaillant\/","og_locale":"fr_FR","og_type":"article","og_title":"R\u00e9parer un syst\u00e8me de ventilation d\u00e9faillant","og_description":"Dans le cas que je vous pr\u00e9sente aujourd&rsquo;hui, comprendre le fonctionnement du syst\u00e8me \u00e9tait essentiel pour r\u00e9soudre le probl\u00e8me. Une mini-fourgonnette Toyota Sienna 2018 nous a \u00e9t\u00e9 amen\u00e9e, le client se plaignant que le ventilateur \u00e9tait bloqu\u00e9 sur la position haute, avec un affichage vide du panneau de contr\u00f4le HVAC (syst\u00e8me de chauffage, de ventilation...","og_url":"https:\/\/autosphere.ca\/fr\/mecanique\/2023\/01\/24\/reparer-un-systeme-de-ventilation-defaillant\/","og_site_name":"Autosphere","article_publisher":"https:\/\/www.facebook.com\/autosphere.ca","article_published_time":"2023-01-24T22:16:33+00:00","og_image":[{"width":758,"height":585,"url":"https:\/\/autosphere.ca\/wp-content\/uploads\/2022\/08\/Mark-Lemay.jpg","type":"image\/jpeg"}],"author":"Mark Lemay","twitter_card":"summary_large_image","twitter_creator":"@autosphere_ca","twitter_site":"@autosphere_ca","twitter_misc":{"\u00c9crit par":"Mark Lemay","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/autosphere.ca\/fr\/mecanique\/2023\/01\/24\/reparer-un-systeme-de-ventilation-defaillant\/#article","isPartOf":{"@id":"https:\/\/autosphere.ca\/fr\/mecanique\/2023\/01\/24\/reparer-un-systeme-de-ventilation-defaillant\/"},"author":{"name":"Mark Lemay","@id":"https:\/\/autosphere.ca\/fr\/#\/schema\/person\/d077f1cf0dd6393fef2f239b7b4fbbca"},"headline":"R\u00e9parer un syst\u00e8me de ventilation d\u00e9faillant","datePublished":"2023-01-24T22:16:33+00:00","mainEntityOfPage":{"@id":"https:\/\/autosphere.ca\/fr\/mecanique\/2023\/01\/24\/reparer-un-systeme-de-ventilation-defaillant\/"},"wordCount":910,"commentCount":0,"publisher":{"@id":"https:\/\/autosphere.ca\/fr\/#organization"},"image":{"@id":"https:\/\/autosphere.ca\/fr\/mecanique\/2023\/01\/24\/reparer-un-systeme-de-ventilation-defaillant\/#primaryimage"},"thumbnailUrl":"https:\/\/autosphere.ca\/wp-content\/uploads\/2022\/08\/Mark-Lemay.jpg","keywords":["Entretien et r\u00e9paration"],"articleSection":["Actualit\u00e9s m\u00e9caniques","M\u00e9canique"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/autosphere.ca\/fr\/mecanique\/2023\/01\/24\/reparer-un-systeme-de-ventilation-defaillant\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/autosphere.ca\/#organization"}},{"@type":"WebPage","@id":"https:\/\/autosphere.ca\/fr\/mecanique\/2023\/01\/24\/reparer-un-systeme-de-ventilation-defaillant\/","url":"https:\/\/autosphere.ca\/fr\/mecanique\/2023\/01\/24\/reparer-un-systeme-de-ventilation-defaillant\/","name":"R\u00e9parer un syst\u00e8me de ventilation d\u00e9faillant - Autosphere","isPartOf":{"@id":"https:\/\/autosphere.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/autosphere.ca\/fr\/mecanique\/2023\/01\/24\/reparer-un-systeme-de-ventilation-defaillant\/#primaryimage"},"image":{"@id":"https:\/\/autosphere.ca\/fr\/mecanique\/2023\/01\/24\/reparer-un-systeme-de-ventilation-defaillant\/#primaryimage"},"thumbnailUrl":"https:\/\/autosphere.ca\/wp-content\/uploads\/2022\/08\/Mark-Lemay.jpg","datePublished":"2023-01-24T22:16:33+00:00","breadcrumb":{"@id":"https:\/\/autosphere.ca\/fr\/mecanique\/2023\/01\/24\/reparer-un-systeme-de-ventilation-defaillant\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/autosphere.ca\/fr\/mecanique\/2023\/01\/24\/reparer-un-systeme-de-ventilation-defaillant\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/autosphere.ca\/fr\/mecanique\/2023\/01\/24\/reparer-un-systeme-de-ventilation-defaillant\/#primaryimage","url":"https:\/\/autosphere.ca\/wp-content\/uploads\/2022\/08\/Mark-Lemay.jpg","contentUrl":"https:\/\/autosphere.ca\/wp-content\/uploads\/2022\/08\/Mark-Lemay.jpg","width":758,"height":585,"caption":"Mark Lemay, Pr\u00e9sident, Auto Aide Technical Services. Source : Mark Lemay"},{"@type":"BreadcrumbList","@id":"https:\/\/autosphere.ca\/fr\/mecanique\/2023\/01\/24\/reparer-un-systeme-de-ventilation-defaillant\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Autosphere","item":"https:\/\/autosphere.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"M\u00e9canique","item":"https:\/\/autosphere.ca\/fr\/category\/mecanique\/"},{"@type":"ListItem","position":3,"name":"R\u00e9parer un syst\u00e8me de ventilation d\u00e9faillant"}]},{"@type":"WebSite","@id":"https:\/\/autosphere.ca\/fr\/#website","url":"https:\/\/autosphere.ca\/fr\/","name":"Autosphere","description":"Articles et nouvelles de l&#039;industrie automobile","publisher":{"@id":"https:\/\/autosphere.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/autosphere.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/autosphere.ca\/fr\/#organization","name":"Autosphere","url":"https:\/\/autosphere.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/autosphere.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/autosphere.ca\/wp-content\/uploads\/2021\/06\/AutosphereLogo-SM.png","contentUrl":"https:\/\/autosphere.ca\/wp-content\/uploads\/2021\/06\/AutosphereLogo-SM.png","width":586,"height":586,"caption":"Autosphere"},"image":{"@id":"https:\/\/autosphere.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/autosphere.ca","https:\/\/x.com\/autosphere_ca","https:\/\/www.linkedin.com\/company\/autosphere-en"]},{"@type":"Person","@id":"https:\/\/autosphere.ca\/fr\/#\/schema\/person\/d077f1cf0dd6393fef2f239b7b4fbbca","name":"Mark Lemay","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/autosphere.ca\/wp-content\/uploads\/2022\/08\/cropped-Mark-Lemay-96x96.jpg","url":"https:\/\/autosphere.ca\/wp-content\/uploads\/2022\/08\/cropped-Mark-Lemay-96x96.jpg","contentUrl":"https:\/\/autosphere.ca\/wp-content\/uploads\/2022\/08\/cropped-Mark-Lemay-96x96.jpg","caption":"Mark Lemay"},"description":"Mark Lemay is President of Auto Aide Technical Services. You can reach him at: markl@autoaide.ca Mark Lemay est le pr\u00e9sident de Auto Aide Technical Services. Vous pouvez le joindre \u00e0 l\u2019adresse suivante : markl@autoaide.ca","url":"https:\/\/autosphere.ca\/fr\/author\/mlemay\/"}]}},"_links":{"self":[{"href":"https:\/\/autosphere.ca\/fr\/wp-json\/wp\/v2\/posts\/378618","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/autosphere.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/autosphere.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/autosphere.ca\/fr\/wp-json\/wp\/v2\/users\/179"}],"replies":[{"embeddable":true,"href":"https:\/\/autosphere.ca\/fr\/wp-json\/wp\/v2\/comments?post=378618"}],"version-history":[{"count":0,"href":"https:\/\/autosphere.ca\/fr\/wp-json\/wp\/v2\/posts\/378618\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/autosphere.ca\/fr\/wp-json\/wp\/v2\/media\/368042"}],"wp:attachment":[{"href":"https:\/\/autosphere.ca\/fr\/wp-json\/wp\/v2\/media?parent=378618"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/autosphere.ca\/fr\/wp-json\/wp\/v2\/categories?post=378618"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/autosphere.ca\/fr\/wp-json\/wp\/v2\/tags?post=378618"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}