{"id":376883,"date":"2022-12-16T08:40:15","date_gmt":"2022-12-16T13:40:15","guid":{"rendered":"https:\/\/autosphere.ca\/?p=376883"},"modified":"2022-12-16T08:44:09","modified_gmt":"2022-12-16T13:44:09","slug":"recharge-entretien-des-ve","status":"publish","type":"post","link":"https:\/\/autosphere.ca\/fr\/parc\/2022\/12\/16\/recharge-entretien-des-ve\/","title":{"rendered":"Recharge &#038; entretien des V\u00c9"},"content":{"rendered":"<div>\n<p><b>L&rsquo;acquisition d&rsquo;un v\u00e9hicule \u00e9lectrique ne se limite pas au v\u00e9hicule lui-m\u00eame.<\/b><\/p>\n<p>General Motors a commenc\u00e9 la production du fourgon commercial \u00e0 moteur \u00e9lectrique BrightDrop \u00e0 Ingersoll, en Ontario. Avec Lion au Qu\u00e9bec, il y a maintenant deux usines d&rsquo;assemblage au Canada qui produisent des v\u00e9hicules enti\u00e8rement \u00e9lectriques pour les clients des parcs.<\/p>\n<p>Le jour o\u00f9 de plus en plus de gestionnaires de parcs d\u00e9cideront de commander le premier v\u00e9hicule \u00e9lectrique pour leur organisation se rapproche.<\/p>\n<h2><b>Chargement de la batterie<\/b><\/h2>\n<p>Le meilleur point de d\u00e9part n&rsquo;est pas le choix du v\u00e9hicule, mais la fa\u00e7on dont la batterie du v\u00e9hicule sera charg\u00e9e. L&rsquo;un des avantages d&rsquo;un v\u00e9hicule \u00e9lectrique est qu&rsquo;il peut \u00eatre recharg\u00e9 lorsqu&rsquo;il n&rsquo;est pas utilis\u00e9. L&rsquo;analyse de rentabilit\u00e9 d&rsquo;un v\u00e9hicule \u00e9lectrique est am\u00e9lior\u00e9e si le v\u00e9hicule est gar\u00e9 la nuit, ce qui laisse beaucoup de temps pour la recharge \u00e0 un moment o\u00f9 les prix de l&rsquo;\u00e9lectricit\u00e9 sont g\u00e9n\u00e9ralement plus bas que pendant la journ\u00e9e.<\/p>\n<p>La premi\u00e8re d\u00e9cision \u00e0 prendre est donc de savoir o\u00f9 le v\u00e9hicule sera charg\u00e9. L&#8217;employ\u00e9 le ram\u00e8nera-t-il chez lui et le chargera-t-il sur place, ou sur le lieu de travail ?<\/p>\n<p>Concentrons-nous sur la recharge sur le lieu de travail. On dit que personne n&rsquo;escalade le mont Everest tout seul, il est donc recommand\u00e9 que ce soit un projet d&rsquo;\u00e9quipe, quelle que soit la taille de la station de recharge. Le gestionnaire des installations est un acteur cl\u00e9 dans ce domaine.<\/p>\n<p>N&rsquo;oubliez pas non plus que le terme \u00ab chargeur \u00bb est utilis\u00e9 \u00e0 tort et \u00e0 travers pour d\u00e9signer ce que l&rsquo;on appelle \u00e0 juste titre EVSE ou \u00e9quipement d&rsquo;alimentation des v\u00e9hicules \u00e9lectriques. Un chargeur est un dispositif dans le v\u00e9hicule qui convertit le courant alternatif en courant continu et contr\u00f4le le flux d&rsquo;\u00e9nergie dans les batteries pour \u00e9viter de les endommager.<\/p>\n<h2><b>Consultation des fournisseurs de services publics<\/b><\/h2>\n<p>Il faut consulter le service de distribution d&rsquo;\u00e9lectricit\u00e9. Le raccordement au r\u00e9seau et l&rsquo;infrastructure du site doivent \u00eatre dimensionn\u00e9s en fonction de la demande \u00e9lectrique pour la recharge. Le propri\u00e9taire du parc doit pr\u00e9voir combien de v\u00e9hicules seront en charge plusieurs ann\u00e9es \u00e0 l&rsquo;avance, m\u00eame si l&rsquo;\u00e9quipement sera \u00e9tendu ult\u00e9rieurement. Il est parfois impossible pour le service public d&rsquo;ajouter un service suppl\u00e9mentaire \u00e0 un site existant. Si c&rsquo;est le cas, il faut trouver un site alternatif.<\/p>\n<p>Un autre avantage des v\u00e9hicules \u00e9lectriques est que le co\u00fbt de l&rsquo;\u00e9lectricit\u00e9 pour couvrir la m\u00eame distance est bien inf\u00e9rieur \u00e0 celui des autres carburants. Mais il faut la g\u00e9rer. Les \u00ab frais de demande \u00bb sont des suppl\u00e9ments d&rsquo;\u00e9lectricit\u00e9 qui interviennent lors des pics d&rsquo;utilisation et peuvent \u00eatre pr\u00e9lev\u00e9s par le service public si la consommation d&rsquo;\u00e9lectricit\u00e9 est trop importante \u00e0 certains moments de la journ\u00e9e. Si le site pr\u00e9sente par ailleurs une faible demande d&rsquo;\u00e9lectricit\u00e9, comme un bureau ou un entrep\u00f4t, les frais de demande doivent \u00eatre g\u00e9r\u00e9s pour r\u00e9duire les co\u00fbts d&rsquo;\u00e9lectricit\u00e9.<\/p>\n<p>Des stations de recharge publiques pourraient \u00eatre utilis\u00e9es \u00e0 la place d&rsquo;une installation sur site, mais cela implique d&rsquo;interrompre l&rsquo;utilisation quotidienne du v\u00e9hicule pour le recharger pendant son utilisation et de perdre du temps suppl\u00e9mentaire si la station la plus proche est occup\u00e9e ou hors service. Le co\u00fbt de la recharge publique n&rsquo;est pas r\u00e9glement\u00e9 et est loin d&rsquo;\u00eatre aussi comp\u00e9titif que celui de l&rsquo;essence au d\u00e9tail. Les prix de facturation peuvent varier consid\u00e9rablement en fonction du fournisseur.<\/p>\n<h2><b>Des consid\u00e9rations diff\u00e9rentes en mati\u00e8re d&rsquo;entretien<\/b><\/h2>\n<p>Un autre avantage des v\u00e9hicules \u00e9lectriques est la r\u00e9duction des frais d&rsquo;entretien, car il y a moins de pi\u00e8ces mobiles \u00e0 user. Roger Smith, fondateur et PDG de Fleet Challenge, souligne que les propri\u00e9taires de V\u00c9 ont toujours besoin d&rsquo;un budget pour l&rsquo;entretien. De nombreux \u00e9l\u00e9ments doivent encore faire l&rsquo;objet d&rsquo;un entretien r\u00e9gulier, comme les pneus, la suspension, le chauffage et la climatisation, et oui, les freins, mais pas aussi fr\u00e9quemment qu&rsquo;avant, car les VE sont dot\u00e9s d&rsquo;un syst\u00e8me de freinage par r\u00e9cup\u00e9ration au lieu de s&rsquo;appuyer sur des surfaces de friction pour s&rsquo;arr\u00eater. Les camions moyens et lourds EV devront faire l&rsquo;objet d&rsquo;inspections annuelles, conform\u00e9ment \u00e0 la r\u00e9glementation provinciale.<\/p>\n<p>Les v\u00e9hicules \u00e9lectriques repr\u00e9sentent le prochain grand d\u00e9fi en mati\u00e8re de gestion de parc et ils ne mobiliseront pas seulement le gestionnaire de parc dans une organisation. Un bon point de d\u00e9part est d&rsquo;avoir un plan qui pr\u00e9voit les exigences en mati\u00e8re de charge.<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;acquisition d&rsquo;un v\u00e9hicule \u00e9lectrique ne se limite pas au v\u00e9hicule lui-m\u00eame. General Motors a commenc\u00e9 la production du fourgon commercial \u00e0 moteur \u00e9lectrique BrightDrop \u00e0 Ingersoll, en Ontario. Avec Lion au Qu\u00e9bec, il y a maintenant deux usines d&rsquo;assemblage au Canada qui produisent des v\u00e9hicules enti\u00e8rement \u00e9lectriques pour les clients des parcs. Le jour o\u00f9&#8230;<\/p>\n","protected":false},"author":134,"featured_media":369254,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[809,621],"tags":[3832],"class_list":["post-376883","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-parc-chronique","category-parc","tag-gestion"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v27.7) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Recharge &amp; entretien des V\u00c9 - Autosphere<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/autosphere.ca\/fr\/parc\/2022\/12\/16\/recharge-entretien-des-ve\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Recharge &amp; entretien des V\u00c9\" \/>\n<meta property=\"og:description\" content=\"L&rsquo;acquisition d&rsquo;un v\u00e9hicule \u00e9lectrique ne se limite pas au v\u00e9hicule lui-m\u00eame. General Motors a commenc\u00e9 la production du fourgon commercial \u00e0 moteur \u00e9lectrique BrightDrop \u00e0 Ingersoll, en Ontario. Avec Lion au Qu\u00e9bec, il y a maintenant deux usines d&rsquo;assemblage au Canada qui produisent des v\u00e9hicules enti\u00e8rement \u00e9lectriques pour les clients des parcs. Le jour o\u00f9...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/autosphere.ca\/fr\/parc\/2022\/12\/16\/recharge-entretien-des-ve\/\" \/>\n<meta property=\"og:site_name\" content=\"Autosphere\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/autosphere.ca\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-16T13:40:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-16T13:44:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/autosphere.ca\/wp-content\/uploads\/2022\/09\/Chris-Hill.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"758\" \/>\n\t<meta property=\"og:image:height\" content=\"585\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Chris Hill\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@autosphere_ca\" \/>\n<meta name=\"twitter:site\" content=\"@autosphere_ca\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Chris Hill\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/parc\\\/2022\\\/12\\\/16\\\/recharge-entretien-des-ve\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/parc\\\/2022\\\/12\\\/16\\\/recharge-entretien-des-ve\\\/\"},\"author\":{\"name\":\"Chris Hill\",\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/#\\\/schema\\\/person\\\/57fd41fa4e33f6b6b9b059e175951cb3\"},\"headline\":\"Recharge &#038; entretien des V\u00c9\",\"datePublished\":\"2022-12-16T13:40:15+00:00\",\"dateModified\":\"2022-12-16T13:44:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/parc\\\/2022\\\/12\\\/16\\\/recharge-entretien-des-ve\\\/\"},\"wordCount\":835,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/parc\\\/2022\\\/12\\\/16\\\/recharge-entretien-des-ve\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/autosphere.ca\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Chris-Hill.jpg\",\"keywords\":[\"Gestion\"],\"articleSection\":[\"Chroniques d\u2019experts de parc automobile\",\"Parc\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/autosphere.ca\\\/fr\\\/parc\\\/2022\\\/12\\\/16\\\/recharge-entretien-des-ve\\\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/autosphere.ca\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/parc\\\/2022\\\/12\\\/16\\\/recharge-entretien-des-ve\\\/\",\"url\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/parc\\\/2022\\\/12\\\/16\\\/recharge-entretien-des-ve\\\/\",\"name\":\"Recharge & entretien des V\u00c9 - Autosphere\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/parc\\\/2022\\\/12\\\/16\\\/recharge-entretien-des-ve\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/parc\\\/2022\\\/12\\\/16\\\/recharge-entretien-des-ve\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/autosphere.ca\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Chris-Hill.jpg\",\"datePublished\":\"2022-12-16T13:40:15+00:00\",\"dateModified\":\"2022-12-16T13:44:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/parc\\\/2022\\\/12\\\/16\\\/recharge-entretien-des-ve\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/autosphere.ca\\\/fr\\\/parc\\\/2022\\\/12\\\/16\\\/recharge-entretien-des-ve\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/parc\\\/2022\\\/12\\\/16\\\/recharge-entretien-des-ve\\\/#primaryimage\",\"url\":\"https:\\\/\\\/autosphere.ca\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Chris-Hill.jpg\",\"contentUrl\":\"https:\\\/\\\/autosphere.ca\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Chris-Hill.jpg\",\"width\":758,\"height\":585},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/parc\\\/2022\\\/12\\\/16\\\/recharge-entretien-des-ve\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Autosphere\",\"item\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Parc\",\"item\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/category\\\/parc\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Recharge &#038; entretien des V\u00c9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/\",\"name\":\"Autosphere\",\"description\":\"Articles et nouvelles de l&#039;industrie automobile\",\"publisher\":{\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/#organization\",\"name\":\"Autosphere\",\"url\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/autosphere.ca\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/AutosphereLogo-SM.png\",\"contentUrl\":\"https:\\\/\\\/autosphere.ca\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/AutosphereLogo-SM.png\",\"width\":586,\"height\":586,\"caption\":\"Autosphere\"},\"image\":{\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/autosphere.ca\",\"https:\\\/\\\/x.com\\\/autosphere_ca\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/autosphere-en\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/#\\\/schema\\\/person\\\/57fd41fa4e33f6b6b9b059e175951cb3\",\"name\":\"Chris Hill\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/autosphere.ca\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/cropped-Chris-Hill-96x96.jpg\",\"url\":\"https:\\\/\\\/autosphere.ca\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/cropped-Chris-Hill-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/autosphere.ca\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/cropped-Chris-Hill-96x96.jpg\",\"caption\":\"Chris Hill\"},\"description\":\"Fleet manager and consultant with some of Canada\u2019s best-known companies and several municipalities, Chris Hill is currently working for the City of Waterloo, Ontario. He also served twice as Chair of NAFA's Ontario Chapter. Gestionnaire de parc et consultant ayant travaill\u00e9 avec certaines des entreprises les plus reconnues au Canada ainsi qu\u2019avec plusieurs municipalit\u00e9s, Chris Hill travaille actuellement pour la Ville de Waterloo, en Ontario. Il a \u00e9galement occup\u00e9 \u00e0 deux reprises le poste de pr\u00e9sident de la section ontarienne de la NAFA.\",\"sameAs\":[\"https:\\\/\\\/autosphere.ca\"],\"url\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/author\\\/chill\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Recharge & entretien des V\u00c9 - Autosphere","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/autosphere.ca\/fr\/parc\/2022\/12\/16\/recharge-entretien-des-ve\/","og_locale":"fr_FR","og_type":"article","og_title":"Recharge & entretien des V\u00c9","og_description":"L&rsquo;acquisition d&rsquo;un v\u00e9hicule \u00e9lectrique ne se limite pas au v\u00e9hicule lui-m\u00eame. General Motors a commenc\u00e9 la production du fourgon commercial \u00e0 moteur \u00e9lectrique BrightDrop \u00e0 Ingersoll, en Ontario. Avec Lion au Qu\u00e9bec, il y a maintenant deux usines d&rsquo;assemblage au Canada qui produisent des v\u00e9hicules enti\u00e8rement \u00e9lectriques pour les clients des parcs. Le jour o\u00f9...","og_url":"https:\/\/autosphere.ca\/fr\/parc\/2022\/12\/16\/recharge-entretien-des-ve\/","og_site_name":"Autosphere","article_publisher":"https:\/\/www.facebook.com\/autosphere.ca","article_published_time":"2022-12-16T13:40:15+00:00","article_modified_time":"2022-12-16T13:44:09+00:00","og_image":[{"width":758,"height":585,"url":"https:\/\/autosphere.ca\/wp-content\/uploads\/2022\/09\/Chris-Hill.jpg","type":"image\/jpeg"}],"author":"Chris Hill","twitter_card":"summary_large_image","twitter_creator":"@autosphere_ca","twitter_site":"@autosphere_ca","twitter_misc":{"\u00c9crit par":"Chris Hill","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/autosphere.ca\/fr\/parc\/2022\/12\/16\/recharge-entretien-des-ve\/#article","isPartOf":{"@id":"https:\/\/autosphere.ca\/fr\/parc\/2022\/12\/16\/recharge-entretien-des-ve\/"},"author":{"name":"Chris Hill","@id":"https:\/\/autosphere.ca\/fr\/#\/schema\/person\/57fd41fa4e33f6b6b9b059e175951cb3"},"headline":"Recharge &#038; entretien des V\u00c9","datePublished":"2022-12-16T13:40:15+00:00","dateModified":"2022-12-16T13:44:09+00:00","mainEntityOfPage":{"@id":"https:\/\/autosphere.ca\/fr\/parc\/2022\/12\/16\/recharge-entretien-des-ve\/"},"wordCount":835,"commentCount":0,"publisher":{"@id":"https:\/\/autosphere.ca\/fr\/#organization"},"image":{"@id":"https:\/\/autosphere.ca\/fr\/parc\/2022\/12\/16\/recharge-entretien-des-ve\/#primaryimage"},"thumbnailUrl":"https:\/\/autosphere.ca\/wp-content\/uploads\/2022\/09\/Chris-Hill.jpg","keywords":["Gestion"],"articleSection":["Chroniques d\u2019experts de parc automobile","Parc"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/autosphere.ca\/fr\/parc\/2022\/12\/16\/recharge-entretien-des-ve\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/autosphere.ca\/#organization"}},{"@type":"WebPage","@id":"https:\/\/autosphere.ca\/fr\/parc\/2022\/12\/16\/recharge-entretien-des-ve\/","url":"https:\/\/autosphere.ca\/fr\/parc\/2022\/12\/16\/recharge-entretien-des-ve\/","name":"Recharge & entretien des V\u00c9 - Autosphere","isPartOf":{"@id":"https:\/\/autosphere.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/autosphere.ca\/fr\/parc\/2022\/12\/16\/recharge-entretien-des-ve\/#primaryimage"},"image":{"@id":"https:\/\/autosphere.ca\/fr\/parc\/2022\/12\/16\/recharge-entretien-des-ve\/#primaryimage"},"thumbnailUrl":"https:\/\/autosphere.ca\/wp-content\/uploads\/2022\/09\/Chris-Hill.jpg","datePublished":"2022-12-16T13:40:15+00:00","dateModified":"2022-12-16T13:44:09+00:00","breadcrumb":{"@id":"https:\/\/autosphere.ca\/fr\/parc\/2022\/12\/16\/recharge-entretien-des-ve\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/autosphere.ca\/fr\/parc\/2022\/12\/16\/recharge-entretien-des-ve\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/autosphere.ca\/fr\/parc\/2022\/12\/16\/recharge-entretien-des-ve\/#primaryimage","url":"https:\/\/autosphere.ca\/wp-content\/uploads\/2022\/09\/Chris-Hill.jpg","contentUrl":"https:\/\/autosphere.ca\/wp-content\/uploads\/2022\/09\/Chris-Hill.jpg","width":758,"height":585},{"@type":"BreadcrumbList","@id":"https:\/\/autosphere.ca\/fr\/parc\/2022\/12\/16\/recharge-entretien-des-ve\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Autosphere","item":"https:\/\/autosphere.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Parc","item":"https:\/\/autosphere.ca\/fr\/category\/parc\/"},{"@type":"ListItem","position":3,"name":"Recharge &#038; entretien des V\u00c9"}]},{"@type":"WebSite","@id":"https:\/\/autosphere.ca\/fr\/#website","url":"https:\/\/autosphere.ca\/fr\/","name":"Autosphere","description":"Articles et nouvelles de l&#039;industrie automobile","publisher":{"@id":"https:\/\/autosphere.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/autosphere.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/autosphere.ca\/fr\/#organization","name":"Autosphere","url":"https:\/\/autosphere.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/autosphere.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/autosphere.ca\/wp-content\/uploads\/2021\/06\/AutosphereLogo-SM.png","contentUrl":"https:\/\/autosphere.ca\/wp-content\/uploads\/2021\/06\/AutosphereLogo-SM.png","width":586,"height":586,"caption":"Autosphere"},"image":{"@id":"https:\/\/autosphere.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/autosphere.ca","https:\/\/x.com\/autosphere_ca","https:\/\/www.linkedin.com\/company\/autosphere-en"]},{"@type":"Person","@id":"https:\/\/autosphere.ca\/fr\/#\/schema\/person\/57fd41fa4e33f6b6b9b059e175951cb3","name":"Chris Hill","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/autosphere.ca\/wp-content\/uploads\/2022\/09\/cropped-Chris-Hill-96x96.jpg","url":"https:\/\/autosphere.ca\/wp-content\/uploads\/2022\/09\/cropped-Chris-Hill-96x96.jpg","contentUrl":"https:\/\/autosphere.ca\/wp-content\/uploads\/2022\/09\/cropped-Chris-Hill-96x96.jpg","caption":"Chris Hill"},"description":"Fleet manager and consultant with some of Canada\u2019s best-known companies and several municipalities, Chris Hill is currently working for the City of Waterloo, Ontario. He also served twice as Chair of NAFA's Ontario Chapter. Gestionnaire de parc et consultant ayant travaill\u00e9 avec certaines des entreprises les plus reconnues au Canada ainsi qu\u2019avec plusieurs municipalit\u00e9s, Chris Hill travaille actuellement pour la Ville de Waterloo, en Ontario. Il a \u00e9galement occup\u00e9 \u00e0 deux reprises le poste de pr\u00e9sident de la section ontarienne de la NAFA.","sameAs":["https:\/\/autosphere.ca"],"url":"https:\/\/autosphere.ca\/fr\/author\/chill\/"}]}},"_links":{"self":[{"href":"https:\/\/autosphere.ca\/fr\/wp-json\/wp\/v2\/posts\/376883","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/autosphere.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/autosphere.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/autosphere.ca\/fr\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/autosphere.ca\/fr\/wp-json\/wp\/v2\/comments?post=376883"}],"version-history":[{"count":0,"href":"https:\/\/autosphere.ca\/fr\/wp-json\/wp\/v2\/posts\/376883\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/autosphere.ca\/fr\/wp-json\/wp\/v2\/media\/369254"}],"wp:attachment":[{"href":"https:\/\/autosphere.ca\/fr\/wp-json\/wp\/v2\/media?parent=376883"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/autosphere.ca\/fr\/wp-json\/wp\/v2\/categories?post=376883"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/autosphere.ca\/fr\/wp-json\/wp\/v2\/tags?post=376883"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}