{"id":341871,"date":"2021-08-02T08:00:14","date_gmt":"2021-08-02T12:00:14","guid":{"rendered":"https:\/\/autosphere.ca\/?p=341871"},"modified":"2022-03-07T14:43:08","modified_gmt":"2022-03-07T19:43:08","slug":"shell-fleet-solutions-transition-energetique","status":"publish","type":"post","link":"https:\/\/autosphere.ca\/fr\/parc\/2021\/08\/02\/shell-fleet-solutions-transition-energetique\/","title":{"rendered":"Shell Fleet Solutions : Transition \u00e9nerg\u00e9tique"},"content":{"rendered":"<p><strong>Shell Fleet Solutions aide les parcs \u00e0 s\u2019engager pour un avenir plus durable.<\/strong><\/p>\n<p>Dans le domaine des parcs, Shell est reconnu comme fournisseur de carburant et Shell Fleet Solutions comme partenaire en gestion de carburant. Shell \u00e9volue et vise \u00e0 devenir une entreprise \u00e9nerg\u00e9tique carboneutre d\u2019ici 2050, en phase avec la soci\u00e9t\u00e9 et sa client\u00e8le.<\/p>\n<p>\u00ab Nous comprenons les nombreux d\u00e9fis auxquels sont confront\u00e9s les parcs dans leur qu\u00eate d\u2019un avenir plus sobre en carbone \u00bb, affirme Sasha Arasteh, responsable des services de mobilit\u00e9, Shell Fleet Solutions, Am\u00e9rique du Nord.<\/p>\n<p>Les gestionnaires sont soumis \u00e0 une pression publique et r\u00e9glementaire constante pour r\u00e9duire la consommation, les \u00e9missions et la congestion et contribuer \u00e0 divers objectifs commerciaux et soci\u00e9taux.<\/p>\n<p>\u00ab Pour r\u00e9pondre efficacement \u00e0 l\u2019\u00e9volution des besoins des gestionnaires de parcs, nous adoptons une approche \u00e0 trois volets qui peut aider votre entreprise \u00e0 identifier les moyens d\u2019\u00e9viter les \u00e9missions de carbone, \u00e0 mettre en \u00e9vidence les possibilit\u00e9s de r\u00e9duction des \u00e9missions<br \/>\net \u00e0 offrir un moyen efficace de compenser les \u00e9missions in\u00e9vitables. \u00bb<\/p>\n<h5><strong>Offre de carburants de remplacement<\/strong><\/h5>\n<p>\u00c0 l\u2019heure o\u00f9 le monde passe des moteurs \u00e0 combustion interne traditionnels \u00e0 des solutions alternatives d\u2019\u00e9nergie et de mobilit\u00e9 \u00e0 faible teneur en carbone, le plan de Shell pour des \u00e9missions nettes nulles comprend des carburants alternatifs, comme l\u2019hydrog\u00e8ne.<\/p>\n<p>\u00ab Au Canada, nous avons deux sites \u00e0 Vancouver qui proposent le ravitaillement en hydrog\u00e8ne \u00bb, indique Mme Arasteh.<\/p>\n<p>Les parcs automobiles modernes \u00e9voluent. Certains s\u2019orientent progressivement vers les v\u00e9hicules \u00e9lectriques ou hybrides, tandis que d\u2019autres ont fait le grand saut et ont besoin de bornes de recharge fiables sur place ou au domicile de leurs employ\u00e9s, ainsi que d\u2019un acc\u00e8s facile \u00e0 un large \u00e9ventail d\u2019options de recharge pendant leurs d\u00e9placements.<\/p>\n<p>Shell s\u2019efforce de r\u00e9pondre aux besoins de recharge des conducteurs de v\u00e9hicules \u00e9lectriques \u2014 \u00e0 la maison, au travail ou sur la route \u2014 gr\u00e2ce \u00e0 un r\u00e9seau de recharge pour v\u00e9hicules \u00e9lectriques en pleine expansion.<\/p>\n<h5><strong>Obtention de renseignements\u00a0gr\u00e2ce \u00e0 Shell Telematics<\/strong><\/h5>\n<p>Shell Telematics est un produit du portfolio de Shell Fleet Solutions qui peut aider les clients \u00e0 r\u00e9duire leurs \u00e9missions de carbone.<\/p>\n<p>En regroupant les donn\u00e9es relatives aux cartes Shell Fleet et aux v\u00e9hicules, la solution t\u00e9l\u00e9matique compl\u00e8te de Shell simplifie tout, du choix d\u2019itin\u00e9raires \u00e9co\u00e9nerg\u00e9tiques au suivi des habitudes de conduite, en passant par la d\u00e9tection de fraude li\u00e9e au carburant.<\/p>\n<p>Shell Telematics vous permet de localiser et de suivre les v\u00e9hicules \u00e0 l\u2019aide d\u2019une carte satellite, de Google Street View et de donn\u00e9es sur la circulation obtenues en temps r\u00e9el, ou presque.<\/p>\n<p>\u00ab Les conducteurs en mesure de choisir des itin\u00e9raires \u00e9conomes en carburant et d\u2019assigner des t\u00e2ches plus efficacement peuvent optimiser les d\u00e9lais de livraison et r\u00e9duire les \u00e9missions inutiles \u00bb, affirme notre interlocutrice.<\/p>\n<p>Shell Telematics fournit \u00e9galement des renseignements pr\u00e9cieux sur le rendement du conducteur.<\/p>\n<p>\u00ab En rep\u00e9rant les comportements d\u00e9favorables tels que la marche au ralenti, les exc\u00e8s de vitesse et les freinages brusques, les gestionnaires peuvent apporter des correctifs afin d\u2019assurer la s\u00e9curit\u00e9 des conducteurs et de r\u00e9duire les accidents, ajoute-t-elle, tout en diminuant les co\u00fbts et les \u00e9missions*. \u00bb<\/p>\n<p>Shell Telematics vous permet d\u2019obtenir des rappels d\u2019entretien et des rapports sur la consommation de carburant.<\/p>\n<p>Vous pouvez activer le g\u00e9orep\u00e9rage et recevoir des alertes et des rapports d\u00e9taill\u00e9s sur les trajets d\u2019un conducteur pour \u00e9tablir le kilom\u00e9trage professionnel et personnel.<\/p>\n<p>\u00ab Tout est g\u00e9r\u00e9 par le biais d\u2019un portail convivial et vous pouvez choisir l\u2019ensemble de fonctionnalit\u00e9s adapt\u00e9 \u00e0 votre entreprise, explique Madame Arasteh. En somme, Shell Telematics procure aux gestionnaires les renseignements n\u00e9cessaires pour optimiser le rendement de leur parc et faire des choix plus durables. \u00bb<\/p>\n<h5><strong>Compensation des \u00e9missions avec des solutions fond\u00e9es sur la nature<\/strong><\/h5>\n<p>Shell Fleet Solutions reconna\u00eet qu\u2019il est parfois impossible d\u2019\u00e9viter les \u00e9missions, d\u2019o\u00f9 l\u2019instauration de son nouveau programme de conduite carboneutre <a href=\"https:\/\/autosphere.ca\/fr\/parc\/2021\/03\/04\/soutenir-les-gestionnaires-de-parcs-en-ces-temps-incertains\/\">permettant aux utilisateurs de la carte Shell Fleet de compenser leurs \u00e9missions de carbone<\/a>.<\/p>\n<p>Selon Sasha Arasteh, l\u2019adoption d\u2019une conduite neutre en carbone est vraiment tr\u00e8s simple.<\/p>\n<p>Une fois inscrit au programme, chaque fois qu\u2019un conducteur utilise sa carte Shell Fleet Navigator ou Shell Fleet Plus pour faire le plein dans une station Shell (\u00e0 l\u2019exception de Shell Flying J), un montant de cr\u00e9dits carbone correspondant ira compenser les \u00e9missions par le biais du portefeuille mondial de projets de solutions fond\u00e9es sur la nature de Shell.<\/p>\n<p>\u00ab Sans compter que vous n\u2019avez m\u00eame pas \u00e0 changer votre fa\u00e7on de travailler \u00bb, souligne-t-elle.<\/p>\n<p>Shell Fleet Solutions enregistre votre consommation de carburant, calcule automatiquement les \u00e9missions associ\u00e9es au cycle de vie et les compense en utilisant un \u00e9ventail mondial de projets fond\u00e9s sur la nature. Les frais sont imput\u00e9s \u00e0 votre compte et Shell \u00e9met chaque ann\u00e9e un certificat valide de r\u00e9duction du carbone confirmant la compensation.<\/p>\n<p>En plus d\u2019att\u00e9nuer l\u2019impact environnemental de votre parc, la compensation des \u00e9missions offre un certain nombre d\u2019avantages commerciaux.<\/p>\n<p>\u00ab Par exemple, vous ferez preuve de leadership, d\u00e9fendrez des pratiques commerciales durables, respecterez vos engagements en mati\u00e8re d\u2019\u00e9missions de carbone et r\u00e9pondrez aux demandes croissantes des employ\u00e9s et autres intervenants en faveur d\u2019actions positives pour l\u2019environnement \u00bb, fait valoir Madame Arasteh.<\/p>\n<h5><strong>Partenariat avec Shell Fleet Solutions<\/strong><\/h5>\n<p>S\u2019associer \u00e0 Shell Fleet Solutions procure certains avantages.<\/p>\n<p>\u00ab Notre r\u00e9seau comprenant 1 350 stations Shell et Shell Flying J est le plus important au Canada \u00bb, affirme notre interlocutrice.<\/p>\n<p>Le localisateur de stations en ligne et l\u2019application de Shell permettent aux conducteurs de trouver rapidement et en tout temps une station \u00e0 proximit\u00e9.<\/p>\n<p>\u00ab Il faut toutefois se rappeler que les cartes Shell Fleet Navigator et Shell Fleet Plus sont plus qu\u2019un simple moyen d\u2019acheter du carburant \u00bb, poursuit Madame Arasteh.<\/p>\n<p>\u00ab Elles permettent aux parcs d\u2019acc\u00e9der \u00e0 tous les renseignements relatifs aux cartes et aux transactions gr\u00e2ce \u00e0 un portail convivial accessible en tout temps. Chaque carte peut \u00eatre personnalis\u00e9e en fixant les limites d\u2019achat non seulement sur le montant de l\u2019achat, mais \u00e9galement le type d\u2019achat, le moment et l\u2019endroit o\u00f9 ils sont effectu\u00e9s. \u00bb<\/p>\n<p>Ce portail permet aux gestionnaires de parcs d\u2019obtenir l\u2019information requise pour g\u00e9rer efficacement leurs d\u00e9penses en carburant.<\/p>\n<p>\u00ab Ils disposent de donn\u00e9es pr\u00e9cises remontant jusqu\u2019\u00e0 la transaction, pr\u00e9cise Madame Arasteh, r\u00e9duisant le risque d\u2019utilisation abusive ou suspecte gr\u00e2ce \u00e0 nos cartes \u00e0 puces avec NIP, \u00e0 l\u2019identification du conducteur et aux diff\u00e9rents contr\u00f4les d\u2019achat que nous proposons aux clients. \u00bb<\/p>\n<p>En s\u2019associant \u00e0 Shell Fleet Solutions, les parcs b\u00e9n\u00e9ficient de r\u00e9ductions sur le carburant, le lavage de v\u00e9hicules et l\u2019entretien.<\/p>\n<p>Bien plus qu\u2019un simple fournisseur de carburant, Shell se positionne en chef de file en aidant les parcs \u00e0 mieux g\u00e9rer leurs op\u00e9rations tout en \u0153uvrant pour un avenir plus durable.<\/p>\n<p>Pour en apprendre davantage sur la fa\u00e7on dont Shell Fleet Solutions peut vous amener l\u00e0 o\u00f9 vous devez aller, visitez <a href=\"http:\/\/shell.ca\/solutionspourparc\">shell.ca\/solutionspourparc<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<p><em>* <strong>Source<\/strong> : <a href=\"https:\/\/www.slideshare.net\/SathyanarayanaK\/frost-sullivans-global-connected-truck-brochure\">Benefits After Effective Deployment of Fleet Management System<\/a>. Frost &amp; Sullivan. 2015. La r\u00e9duction des \u00e9missions varie en fonction du type de v\u00e9hicule et des habitudes de conduite, notamment le temps de marche au ralenti, les exc\u00e8s de vitesse, etc. par rapport aux am\u00e9liorations du v\u00e9hicule.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Shell Fleet Solutions aide les parcs \u00e0 s\u2019engager pour un avenir plus durable. Dans le domaine des parcs, Shell est reconnu comme fournisseur de carburant et Shell Fleet Solutions comme partenaire en gestion de carburant. Shell \u00e9volue et vise \u00e0 devenir une entreprise \u00e9nerg\u00e9tique carboneutre d\u2019ici 2050, en phase avec la soci\u00e9t\u00e9 et sa client\u00e8le&#8230;.<\/p>\n","protected":false},"author":42,"featured_media":341874,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[621,814],"tags":[3747,4603,2659,2893],"class_list":["post-341871","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-parc","category-parc-publicitaire","tag-durabilite","tag-journee-internationale-des-droits-des-femmes","tag-shell-fr","tag-telematique"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v27.7) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Shell Fleet Solutions : Transition \u00e9nerg\u00e9tique - Autosphere<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/autosphere.ca\/fr\/parc\/2021\/08\/02\/shell-fleet-solutions-transition-energetique\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Shell Fleet Solutions : Transition \u00e9nerg\u00e9tique\" \/>\n<meta property=\"og:description\" content=\"Shell Fleet Solutions aide les parcs \u00e0 s\u2019engager pour un avenir plus durable. Dans le domaine des parcs, Shell est reconnu comme fournisseur de carburant et Shell Fleet Solutions comme partenaire en gestion de carburant. Shell \u00e9volue et vise \u00e0 devenir une entreprise \u00e9nerg\u00e9tique carboneutre d\u2019ici 2050, en phase avec la soci\u00e9t\u00e9 et sa client\u00e8le....\" \/>\n<meta property=\"og:url\" content=\"https:\/\/autosphere.ca\/fr\/parc\/2021\/08\/02\/shell-fleet-solutions-transition-energetique\/\" \/>\n<meta property=\"og:site_name\" content=\"Autosphere\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/autosphere.ca\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-02T12:00:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-07T19:43:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/autosphere.ca\/wp-content\/uploads\/2021\/07\/SashaArasteh-ShellFleetSolutions-WP.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"758\" \/>\n\t<meta property=\"og:image:height\" content=\"585\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jack Kazmierski\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@autosphere_ca\" \/>\n<meta name=\"twitter:site\" content=\"@autosphere_ca\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jack Kazmierski\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/parc\\\/2021\\\/08\\\/02\\\/shell-fleet-solutions-transition-energetique\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/parc\\\/2021\\\/08\\\/02\\\/shell-fleet-solutions-transition-energetique\\\/\"},\"author\":{\"name\":\"Jack Kazmierski\",\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/#\\\/schema\\\/person\\\/959ee0a26c4c5a3074bfa7eb8680b921\"},\"headline\":\"Shell Fleet Solutions : Transition \u00e9nerg\u00e9tique\",\"datePublished\":\"2021-08-02T12:00:14+00:00\",\"dateModified\":\"2022-03-07T19:43:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/parc\\\/2021\\\/08\\\/02\\\/shell-fleet-solutions-transition-energetique\\\/\"},\"wordCount\":1278,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/parc\\\/2021\\\/08\\\/02\\\/shell-fleet-solutions-transition-energetique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/autosphere.ca\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/SashaArasteh-ShellFleetSolutions-WP.jpg\",\"keywords\":[\"Durabilit\u00e9\",\"Journ\u00e9e internationale des Droits des Femmes\",\"Shell\",\"T\u00e9l\u00e9matique\"],\"articleSection\":[\"Parc\",\"Publicitaire\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/autosphere.ca\\\/fr\\\/parc\\\/2021\\\/08\\\/02\\\/shell-fleet-solutions-transition-energetique\\\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/autosphere.ca\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/parc\\\/2021\\\/08\\\/02\\\/shell-fleet-solutions-transition-energetique\\\/\",\"url\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/parc\\\/2021\\\/08\\\/02\\\/shell-fleet-solutions-transition-energetique\\\/\",\"name\":\"Shell Fleet Solutions : Transition \u00e9nerg\u00e9tique - Autosphere\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/parc\\\/2021\\\/08\\\/02\\\/shell-fleet-solutions-transition-energetique\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/parc\\\/2021\\\/08\\\/02\\\/shell-fleet-solutions-transition-energetique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/autosphere.ca\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/SashaArasteh-ShellFleetSolutions-WP.jpg\",\"datePublished\":\"2021-08-02T12:00:14+00:00\",\"dateModified\":\"2022-03-07T19:43:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/parc\\\/2021\\\/08\\\/02\\\/shell-fleet-solutions-transition-energetique\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/autosphere.ca\\\/fr\\\/parc\\\/2021\\\/08\\\/02\\\/shell-fleet-solutions-transition-energetique\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/parc\\\/2021\\\/08\\\/02\\\/shell-fleet-solutions-transition-energetique\\\/#primaryimage\",\"url\":\"https:\\\/\\\/autosphere.ca\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/SashaArasteh-ShellFleetSolutions-WP.jpg\",\"contentUrl\":\"https:\\\/\\\/autosphere.ca\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/SashaArasteh-ShellFleetSolutions-WP.jpg\",\"width\":758,\"height\":585,\"caption\":\"Sasha Arasteh shell fleet solutions\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/parc\\\/2021\\\/08\\\/02\\\/shell-fleet-solutions-transition-energetique\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Autosphere\",\"item\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Parc\",\"item\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/category\\\/parc\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Shell Fleet Solutions : Transition \u00e9nerg\u00e9tique\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/\",\"name\":\"Autosphere\",\"description\":\"Articles et nouvelles de l&#039;industrie automobile\",\"publisher\":{\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/#organization\",\"name\":\"Autosphere\",\"url\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/autosphere.ca\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/AutosphereLogo-SM.png\",\"contentUrl\":\"https:\\\/\\\/autosphere.ca\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/AutosphereLogo-SM.png\",\"width\":586,\"height\":586,\"caption\":\"Autosphere\"},\"image\":{\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/autosphere.ca\",\"https:\\\/\\\/x.com\\\/autosphere_ca\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/autosphere-en\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/#\\\/schema\\\/person\\\/959ee0a26c4c5a3074bfa7eb8680b921\",\"name\":\"Jack Kazmierski\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/autosphere.ca\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/cropped-Jack-Kazmierski-96x96.jpg\",\"url\":\"https:\\\/\\\/autosphere.ca\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/cropped-Jack-Kazmierski-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/autosphere.ca\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/cropped-Jack-Kazmierski-96x96.jpg\",\"caption\":\"Jack Kazmierski\"},\"description\":\"Jack Kazmierski is the Editor-in-Chief of Fleet&amp;Mobility. He is an experienced and recognized automotive journalist and photographer, specializing primarily in fleets, dealerships, and tires. Jack Kazmierski est R\u00e9dacteur en chef de Flottes&amp;Mobilit\u00e9. Il est un journaliste et photographe automobile exp\u00e9riment\u00e9 et reconnu, sp\u00e9cialis\u00e9 principalement dans les secteurs des flottes, des concessionnaires et des pneus.\",\"sameAs\":[\"https:\\\/\\\/autosphere.ca\"],\"url\":\"https:\\\/\\\/autosphere.ca\\\/fr\\\/author\\\/jackkazmierski\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Shell Fleet Solutions : Transition \u00e9nerg\u00e9tique - Autosphere","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/autosphere.ca\/fr\/parc\/2021\/08\/02\/shell-fleet-solutions-transition-energetique\/","og_locale":"fr_FR","og_type":"article","og_title":"Shell Fleet Solutions : Transition \u00e9nerg\u00e9tique","og_description":"Shell Fleet Solutions aide les parcs \u00e0 s\u2019engager pour un avenir plus durable. Dans le domaine des parcs, Shell est reconnu comme fournisseur de carburant et Shell Fleet Solutions comme partenaire en gestion de carburant. Shell \u00e9volue et vise \u00e0 devenir une entreprise \u00e9nerg\u00e9tique carboneutre d\u2019ici 2050, en phase avec la soci\u00e9t\u00e9 et sa client\u00e8le....","og_url":"https:\/\/autosphere.ca\/fr\/parc\/2021\/08\/02\/shell-fleet-solutions-transition-energetique\/","og_site_name":"Autosphere","article_publisher":"https:\/\/www.facebook.com\/autosphere.ca","article_published_time":"2021-08-02T12:00:14+00:00","article_modified_time":"2022-03-07T19:43:08+00:00","og_image":[{"width":758,"height":585,"url":"https:\/\/autosphere.ca\/wp-content\/uploads\/2021\/07\/SashaArasteh-ShellFleetSolutions-WP.jpg","type":"image\/jpeg"}],"author":"Jack Kazmierski","twitter_card":"summary_large_image","twitter_creator":"@autosphere_ca","twitter_site":"@autosphere_ca","twitter_misc":{"\u00c9crit par":"Jack Kazmierski","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/autosphere.ca\/fr\/parc\/2021\/08\/02\/shell-fleet-solutions-transition-energetique\/#article","isPartOf":{"@id":"https:\/\/autosphere.ca\/fr\/parc\/2021\/08\/02\/shell-fleet-solutions-transition-energetique\/"},"author":{"name":"Jack Kazmierski","@id":"https:\/\/autosphere.ca\/fr\/#\/schema\/person\/959ee0a26c4c5a3074bfa7eb8680b921"},"headline":"Shell Fleet Solutions : Transition \u00e9nerg\u00e9tique","datePublished":"2021-08-02T12:00:14+00:00","dateModified":"2022-03-07T19:43:08+00:00","mainEntityOfPage":{"@id":"https:\/\/autosphere.ca\/fr\/parc\/2021\/08\/02\/shell-fleet-solutions-transition-energetique\/"},"wordCount":1278,"commentCount":0,"publisher":{"@id":"https:\/\/autosphere.ca\/fr\/#organization"},"image":{"@id":"https:\/\/autosphere.ca\/fr\/parc\/2021\/08\/02\/shell-fleet-solutions-transition-energetique\/#primaryimage"},"thumbnailUrl":"https:\/\/autosphere.ca\/wp-content\/uploads\/2021\/07\/SashaArasteh-ShellFleetSolutions-WP.jpg","keywords":["Durabilit\u00e9","Journ\u00e9e internationale des Droits des Femmes","Shell","T\u00e9l\u00e9matique"],"articleSection":["Parc","Publicitaire"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/autosphere.ca\/fr\/parc\/2021\/08\/02\/shell-fleet-solutions-transition-energetique\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/autosphere.ca\/#organization"}},{"@type":"WebPage","@id":"https:\/\/autosphere.ca\/fr\/parc\/2021\/08\/02\/shell-fleet-solutions-transition-energetique\/","url":"https:\/\/autosphere.ca\/fr\/parc\/2021\/08\/02\/shell-fleet-solutions-transition-energetique\/","name":"Shell Fleet Solutions : Transition \u00e9nerg\u00e9tique - Autosphere","isPartOf":{"@id":"https:\/\/autosphere.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/autosphere.ca\/fr\/parc\/2021\/08\/02\/shell-fleet-solutions-transition-energetique\/#primaryimage"},"image":{"@id":"https:\/\/autosphere.ca\/fr\/parc\/2021\/08\/02\/shell-fleet-solutions-transition-energetique\/#primaryimage"},"thumbnailUrl":"https:\/\/autosphere.ca\/wp-content\/uploads\/2021\/07\/SashaArasteh-ShellFleetSolutions-WP.jpg","datePublished":"2021-08-02T12:00:14+00:00","dateModified":"2022-03-07T19:43:08+00:00","breadcrumb":{"@id":"https:\/\/autosphere.ca\/fr\/parc\/2021\/08\/02\/shell-fleet-solutions-transition-energetique\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/autosphere.ca\/fr\/parc\/2021\/08\/02\/shell-fleet-solutions-transition-energetique\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/autosphere.ca\/fr\/parc\/2021\/08\/02\/shell-fleet-solutions-transition-energetique\/#primaryimage","url":"https:\/\/autosphere.ca\/wp-content\/uploads\/2021\/07\/SashaArasteh-ShellFleetSolutions-WP.jpg","contentUrl":"https:\/\/autosphere.ca\/wp-content\/uploads\/2021\/07\/SashaArasteh-ShellFleetSolutions-WP.jpg","width":758,"height":585,"caption":"Sasha Arasteh shell fleet solutions"},{"@type":"BreadcrumbList","@id":"https:\/\/autosphere.ca\/fr\/parc\/2021\/08\/02\/shell-fleet-solutions-transition-energetique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Autosphere","item":"https:\/\/autosphere.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Parc","item":"https:\/\/autosphere.ca\/fr\/category\/parc\/"},{"@type":"ListItem","position":3,"name":"Shell Fleet Solutions : Transition \u00e9nerg\u00e9tique"}]},{"@type":"WebSite","@id":"https:\/\/autosphere.ca\/fr\/#website","url":"https:\/\/autosphere.ca\/fr\/","name":"Autosphere","description":"Articles et nouvelles de l&#039;industrie automobile","publisher":{"@id":"https:\/\/autosphere.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/autosphere.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/autosphere.ca\/fr\/#organization","name":"Autosphere","url":"https:\/\/autosphere.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/autosphere.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/autosphere.ca\/wp-content\/uploads\/2021\/06\/AutosphereLogo-SM.png","contentUrl":"https:\/\/autosphere.ca\/wp-content\/uploads\/2021\/06\/AutosphereLogo-SM.png","width":586,"height":586,"caption":"Autosphere"},"image":{"@id":"https:\/\/autosphere.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/autosphere.ca","https:\/\/x.com\/autosphere_ca","https:\/\/www.linkedin.com\/company\/autosphere-en"]},{"@type":"Person","@id":"https:\/\/autosphere.ca\/fr\/#\/schema\/person\/959ee0a26c4c5a3074bfa7eb8680b921","name":"Jack Kazmierski","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/autosphere.ca\/wp-content\/uploads\/2026\/03\/cropped-Jack-Kazmierski-96x96.jpg","url":"https:\/\/autosphere.ca\/wp-content\/uploads\/2026\/03\/cropped-Jack-Kazmierski-96x96.jpg","contentUrl":"https:\/\/autosphere.ca\/wp-content\/uploads\/2026\/03\/cropped-Jack-Kazmierski-96x96.jpg","caption":"Jack Kazmierski"},"description":"Jack Kazmierski is the Editor-in-Chief of Fleet&amp;Mobility. He is an experienced and recognized automotive journalist and photographer, specializing primarily in fleets, dealerships, and tires. Jack Kazmierski est R\u00e9dacteur en chef de Flottes&amp;Mobilit\u00e9. Il est un journaliste et photographe automobile exp\u00e9riment\u00e9 et reconnu, sp\u00e9cialis\u00e9 principalement dans les secteurs des flottes, des concessionnaires et des pneus.","sameAs":["https:\/\/autosphere.ca"],"url":"https:\/\/autosphere.ca\/fr\/author\/jackkazmierski\/"}]}},"_links":{"self":[{"href":"https:\/\/autosphere.ca\/fr\/wp-json\/wp\/v2\/posts\/341871","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/autosphere.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/autosphere.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/autosphere.ca\/fr\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/autosphere.ca\/fr\/wp-json\/wp\/v2\/comments?post=341871"}],"version-history":[{"count":0,"href":"https:\/\/autosphere.ca\/fr\/wp-json\/wp\/v2\/posts\/341871\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/autosphere.ca\/fr\/wp-json\/wp\/v2\/media\/341874"}],"wp:attachment":[{"href":"https:\/\/autosphere.ca\/fr\/wp-json\/wp\/v2\/media?parent=341871"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/autosphere.ca\/fr\/wp-json\/wp\/v2\/categories?post=341871"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/autosphere.ca\/fr\/wp-json\/wp\/v2\/tags?post=341871"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}